{"id":7493,"date":"2024-09-06T13:07:20","date_gmt":"2024-09-06T13:07:20","guid":{"rendered":"https:\/\/kickbol.com\/?p=7493"},"modified":"2024-10-05T09:43:30","modified_gmt":"2024-10-05T09:43:30","slug":"borussia-dortmund-vs-mainz","status":"publish","type":"post","link":"https:\/\/kickbol.com\/it\/borussia-dortmund-vs-mainz\/","title":{"rendered":"Borussia Dortmund contro Magonza\u00a0"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM --><div id=\"ls-widget\" data-w=\"w_custom\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/germany\/mainz-borussia-dortmund\/1861102?w=w_custom\" class=\"livescore-widget\"><\/div><script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script><!-- LIVESCORE WIDGET SOCCERSAPI.COM -->\n\n\n\n<p>IL <a href=\"https:\/\/kickbol.com\/it\/bundesliga\/\">Bundesliga<\/a>, rinomato per le sue narrazioni accattivanti e il calcio esaltante, \u00e8 pronto ad assistere a uno scontro tra titani, con Borussia Dortmund e Mainz 05 che si affronteranno nella stagione 2024\/2025. Questo incontro trascende il semplice scambio di gol e contrasti; incarna il ricco arazzo del calcio tedesco, dove storia, tattiche e brillantezza individuale si intrecciano per creare uno spettacolo per tutte le et\u00e0.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Testa a testa: uno sguardo alla rivalit\u00e0<\/strong><\/h3>\n\n\n\n<p>Dortmund e Mainz hanno una storia leggendaria, i loro incontri abbracciano decenni di azione della Bundesliga. Uno sguardo superficiale al loro record testa a testa rivela una rivalit\u00e0 ferocemente contestata, dove ogni partita \u00e8 un campo di battaglia per la supremazia.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Statistica<\/th><th>Borussia Dortmund<\/th><th>Magonza 05<\/th><\/tr><\/thead><tbody><tr><td>Partite giocate<\/td><td>36<\/td><td>36<\/td><\/tr><tr><td>Vince il Dortmund<\/td><td>19<\/td><td>8<\/td><\/tr><tr><td>Vince Magonza<\/td><td>8<\/td><td>19<\/td><\/tr><tr><td>Disegna<\/td><td>9<\/td><td>9<\/td><\/tr><tr><td>Gol segnati<\/td><td>71<\/td><td>52<\/td><\/tr><tr><td>Gol subiti<\/td><td>45<\/td><td>66<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Mentre il Dortmund detiene un leggero vantaggio in termini di vittorie, il Mainz ha costantemente dimostrato di essere un avversario formidabile, capace di sconvolgere l&#039;ordine costituito. Questo contesto storico aggiunge un ulteriore livello di intrigo al prossimo incontro, poich\u00e9 entrambe le squadre cercano di incidere ulteriormente i loro nomi negli annali del folklore della Bundesliga.<\/p>\n\n\n\n<p><strong>Masterclass tattica: stili di gioco contrastanti<\/strong><\/p>\n\n\n\n<p>Il Borussia Dortmund, sotto la tutela del suo astuto allenatore, \u00e8 rinomato per il suo calcio offensivo e ad alto numero di ottani. La sua formazione preferita, il 4-2-3-1, facilita un pressing implacabile, con i terzini che si lanciano in avanti per supportare l&#039;attacco. Il duo di centrocampisti funge da doppio perno, proteggendo la difesa mentre avvia rapide transizioni verso il terzo finale. Il tridente offensivo, composto da ali creative e un regista dinamico, orchestra una sinfonia di movimenti offensivi, mentre l&#039;unica punta funge da punto focale, utilizzando il suo istinto di bracconaggio e la sua abilit\u00e0 aerea con effetti devastanti.<\/p>\n\n\n\n<p>Il Mainz, d&#039;altro canto, adotta un approccio pi\u00f9 pragmatico, enfatizzando la solidit\u00e0 difensiva e la disciplina tattica. La loro formazione 3-4-2-1 fornisce una solida struttura difensiva, con i terzini che si ripiegano per formare una difesa a cinque quando non sono in possesso di palla. I centrocampisti centrali hanno il compito di interrompere il ritmo avversario, mentre i centrocampisti offensivi forniscono una scintilla creativa, collegandosi con l&#039;unica punta. Lo stile di gioco del Mainz \u00e8 una testimonianza della loro incrollabile resilienza e della loro capacit\u00e0 di frustrare anche le pi\u00f9 potenti forze d&#039;attacco.<\/p>\n\n\n\n<p><strong>Complessit\u00e0 formative e attori chiave: i catalizzatori del successo<\/strong><\/p>\n\n\n\n<p>La formazione 4-2-3-1 del Dortmund \u00e8 una macchina ben oliata, in cui ogni ingranaggio gioca un ruolo cruciale nel successo della squadra. I terzini predatori forniscono ampiezza e impeto offensivo, mentre il duo di centrocampo detta il ritmo del gioco, i loro passaggi metronomici danno il tono alle incursioni offensive della squadra. Il tridente offensivo, un mix di ritmo, inganno e visione, \u00e8 un incubo per i difensori avversari, la loro intricata interazione crea una pletora di opportunit\u00e0 di segnare. L&#039;unica punta, un finalizzatore clinico con un talento per essere nel posto giusto al momento giusto, \u00e8 il pezzo finale del puzzle, i suoi istinti predatori assicurano che il dominio del Dortmund si traduca in gol.<\/p>\n\n\n\n<p>La formazione 3-4-2-1 del Mainz \u00e8 un capolavoro di organizzazione difensiva, progettata per soffocare la creativit\u00e0 degli avversari e limitare le loro possibilit\u00e0 di segnare. I tre difensori, un&#039;unit\u00e0 coesa di difensori esperti, sono abili nel leggere il gioco e nell&#039;anticipare il pericolo. I terzini, corridori instancabili con una propensione sia per i contributi difensivi che offensivi, forniscono un ulteriore livello di protezione offrendo anche uno sbocco in attacco. I centrocampisti centrali, combattivi e tenaci, sono la sala macchine della squadra, la loro energia e il loro ritmo di lavoro danno il tono al resto della squadra. I centrocampisti offensivi, incaricati di fornire una scintilla creativa, sono il collegamento tra difesa e attacco, la loro capacit\u00e0 di scegliere un passaggio e creare occasioni per l&#039;unica punta si rivela inestimabile.<\/p>\n\n\n\n<p><strong>Significato storico e migliori marcatori di tutti i tempi: un&#039;eredit\u00e0 di leggende<\/strong><\/p>\n\n\n\n<p>L&#039;illustre storia del Dortmund \u00e8 piena di personaggi leggendari che hanno inciso i loro nomi nel folklore del club. Il loro miglior marcatore di sempre, un attaccante prolifico con una straordinaria capacit\u00e0 di trovare il fondo della rete, \u00e8 venerato dai tifosi come simbolo della bravura offensiva del club. Il Mainz, pur non vantando lo stesso pedigree storico del Dortmund, ha la sua giusta quota di giocatori iconici che hanno lasciato un segno indelebile nella storia del club. Il loro miglior marcatore di sempre, un attaccante versatile con una propensione per lo spettacolare, \u00e8 una testimonianza della capacit\u00e0 del club di coltivare e sviluppare talenti.<\/p>\n\n\n\n<p><strong>Giocatori da tenere d&#039;occhio: stelle emergenti e veterani esperti<\/strong><\/p>\n\n\n\n<p>Mentre Dortmund e Mainz si preparano a rinnovare la loro rivalit\u00e0, diversi giocatori sono pronti a svolgere ruoli cruciali nell&#039;esito della partita. Il giovane e dinamico esterno del Dortmund, con il suo ritmo bruciante e le sue abilit\u00e0 di dribbling ipnotizzanti, \u00e8 una minaccia costante per le difese avversarie. L&#039;esperto portiere del Mainz, un portiere di primissimo ordine, \u00e8 un ostacolo formidabile da superare per qualsiasi attaccante. Le battaglie individuali tra questi giocatori chiave potrebbero benissimo determinare il destino della partita.<\/p>\n\n\n\n<p><strong>Attivit\u00e0 di trasferimento attuale: costruire per il futuro<\/strong><\/p>\n\n\n\n<p>Sia il Dortmund che il Mainz sono stati attivi nel mercato dei trasferimenti, puntando a rafforzare le loro squadre per le sfide che li attendono. Il Dortmund, con la sua forza finanziaria e il suo appeal globale, ha attratto alcuni dei giovani talenti pi\u00f9 promettenti del calcio mondiale. Il Mainz, d&#039;altro canto, ha adottato un approccio pi\u00f9 prudente, concentrandosi sull&#039;acquisizione di giocatori che si adattino al loro sistema tattico e possano avere un impatto immediato sulla squadra. Le attivit\u00e0 di trasferimento di entrambi i club riflettono la loro ambizione e il loro desiderio di competere ai massimi livelli.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusione: ci aspetta uno spettacolo della Bundesliga<\/strong><\/h2>\n\n\n\n<p>Lo scontro tra Dortmund e Mainz \u00e8 una prospettiva allettante, un incontro di due squadre con stili contrastanti, storie ricche e grandi ambizioni. Il Dortmund, i contendenti perenni, cercher\u00e0 di affermare il proprio dominio e continuare la sua ricerca di trofei. Il Mainz, i perdenti resilienti, cercher\u00e0 di sconvolgere l&#039;ordine costituito e dimostrare il proprio valore sul grande palcoscenico.<\/p>\n\n\n\n<p>Questo incontro non \u00e8 semplicemente una partita di calcio; \u00e8 una celebrazione del bel gioco, dove acume tattico, brillantezza individuale e incrollabile spirito di squadra convergono per creare uno spettacolo che catturer\u00e0 i tifosi di tutto il mondo. Mentre le due squadre si preparano a scontrarsi, il mondo del calcio attende con ansia una partita che promette di essere una festa per i sensi.<\/p>\n\n\n\n<p>Il fischio finale segner\u00e0 la fine di novanta minuti di intensa competizione, ma i ricordi di questa partita rimarranno a lungo impressi nella mente di coloro che saranno abbastanza fortunati da assistervi. Sar\u00e0 una storia di sogni inseguiti, di sfide superate e dell&#039;incrollabile spirito competitivo che caratterizza la Bundesliga. Quindi, sediamoci, rilassiamoci e assaporiamo questo avvincente incontro, mentre Dortmund e Mainz aggiungono un altro capitolo alla loro storica rivalit\u00e0.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Bundesliga, renowned for its captivating narratives and exhilarating football, is set to witness a clash of titans as Borussia Dortmund and Mainz 05 square off in the 2024\/2025 season. This encounter transcends the mere exchange of goals and tackles; it embodies the rich tapestry of German football, where history, tactics, and individual brilliance intertwine [&hellip;]<\/p>","protected":false},"author":1,"featured_media":7494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-7493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Borussia Dortmund vs Mainz\u00a0 - Kickbol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/it\/borussia-dortmund-vs-mainz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borussia Dortmund vs Mainz\u00a0 - Kickbol\" \/>\n<meta property=\"og:description\" content=\"The Bundesliga, renowned for its captivating narratives and exhilarating football, is set to witness a clash of titans as Borussia Dortmund and Mainz 05 square off in the 2024\/2025 season. This encounter transcends the mere exchange of goals and tackles; it embodies the rich tapestry of German football, where history, tactics, and individual brilliance intertwine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/it\/borussia-dortmund-vs-mainz\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-06T13:07:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-05T09:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/Dortmund-vs-Mainz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Borussia Dortmund vs Mainz\u00a0\",\"datePublished\":\"2024-09-06T13:07:20+00:00\",\"dateModified\":\"2024-10-05T09:43:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/\"},\"wordCount\":1107,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Dortmund-vs-Mainz.png\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/\",\"name\":\"Borussia Dortmund vs Mainz\u00a0 - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Dortmund-vs-Mainz.png\",\"datePublished\":\"2024-09-06T13:07:20+00:00\",\"dateModified\":\"2024-10-05T09:43:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Dortmund-vs-Mainz.png\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Dortmund-vs-Mainz.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/borussia-dortmund-vs-mainz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Borussia Dortmund vs Mainz\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/it\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borussia Dortmund vs Mainz\u00a0 - Kickbol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/it\/borussia-dortmund-vs-mainz\/","og_locale":"it_IT","og_type":"article","og_title":"Borussia Dortmund vs Mainz\u00a0 - Kickbol","og_description":"The Bundesliga, renowned for its captivating narratives and exhilarating football, is set to witness a clash of titans as Borussia Dortmund and Mainz 05 square off in the 2024\/2025 season. This encounter transcends the mere exchange of goals and tackles; it embodies the rich tapestry of German football, where history, tactics, and individual brilliance intertwine [&hellip;]","og_url":"https:\/\/kickbol.com\/it\/borussia-dortmund-vs-mainz\/","og_site_name":"Kickbol","article_published_time":"2024-09-06T13:07:20+00:00","article_modified_time":"2024-10-05T09:43:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/Dortmund-vs-Mainz.png","type":"image\/png"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Julius","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Borussia Dortmund vs Mainz\u00a0","datePublished":"2024-09-06T13:07:20+00:00","dateModified":"2024-10-05T09:43:30+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/"},"wordCount":1107,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/Dortmund-vs-Mainz.png","articleSection":["Head to Head"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/","url":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/","name":"Borussia Dortmund vs Mainz\u00a0 - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/Dortmund-vs-Mainz.png","datePublished":"2024-09-06T13:07:20+00:00","dateModified":"2024-10-05T09:43:30+00:00","breadcrumb":{"@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/Dortmund-vs-Mainz.png","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/Dortmund-vs-Mainz.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/borussia-dortmund-vs-mainz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Borussia Dortmund vs Mainz\u00a0"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/it\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/posts\/7493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/comments?post=7493"}],"version-history":[{"count":2,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/posts\/7493\/revisions"}],"predecessor-version":[{"id":7881,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/posts\/7493\/revisions\/7881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/media\/7494"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/media?parent=7493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/categories?post=7493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/it\/wp-json\/wp\/v2\/tags?post=7493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}