{"id":8654,"date":"2024-11-10T13:11:49","date_gmt":"2024-11-10T13:11:49","guid":{"rendered":"https:\/\/kickbol.com\/?p=8654"},"modified":"2024-11-10T13:11:50","modified_gmt":"2024-11-10T13:11:50","slug":"magesi-fc-vs-sekhukhune-united","status":"publish","type":"post","link":"https:\/\/kickbol.com\/fr\/magesi-fc-vs-sekhukhune-united\/","title":{"rendered":"Magesi FC contre Sekhukhune United"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM -->                <div id=\"ls-widget\" data-w=\"w_default\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/south-africa\/magesi-sekhukhune-united\/1895518?w=w_default\" class=\"livescore-widget\"><\/div>                <script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script>                <!-- LIVESCORE WIDGET SOCCERSAPI.COM -->                            \n\n\n\n<p>Au coeur de <a href=\"https:\/\/kickbol.com\/fr\/premier-soccer-league\/\">Football sud-africain<\/a>, un r\u00e9cit captivant se d\u00e9roulera alors que le Magesi FC se pr\u00e9pare \u00e0 affronter Sekhukhune United dans une rencontre du Motsepe Foundation Championship qui incarne l&#039;essence m\u00eame du sport : la passion, la r\u00e9silience et la qu\u00eate in\u00e9branlable de la victoire. Les deux \u00e9quipes, aliment\u00e9es par leurs aspirations distinctes, sont pr\u00eates \u00e0 laisser une marque ind\u00e9l\u00e9bile sur la saison 2024\/2025.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Face \u00e0 face : l&#039;histoire d&#039;une rivalit\u00e9 naissante<\/strong><\/h2>\n\n\n\n<p>Si l&#039;histoire entre le Magesi FC et le Sekhukhune United est relativement br\u00e8ve, leurs rencontres ont \u00e9t\u00e9 intenses et \u00e2prement disput\u00e9es. Leur bilan face \u00e0 face t\u00e9moigne d&#039;une rivalit\u00e9 naissante, o\u00f9 chaque match t\u00e9moigne de l&#039;esprit de comp\u00e9tition qui impr\u00e8gne le football sud-africain.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Statistique<\/th><th>FC Magesi<\/th><th>Sekhukhune United<\/th><\/tr><\/thead><tbody><tr><td>Victoires<\/td><td>1<\/td><td>2<\/td><\/tr><tr><td>Pertes<\/td><td>2<\/td><td>1<\/td><\/tr><tr><td>Tirages au sort<\/td><td>0<\/td><td>0<\/td><\/tr><tr><td>Buts marqu\u00e9s<\/td><td>3<\/td><td>5<\/td><\/tr><tr><td>Buts encaiss\u00e9s<\/td><td>5<\/td><td>3<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Match d&#039;\u00e9checs tactique : philosophies de jeu contrast\u00e9es<\/strong><\/h3>\n\n\n\n<p>Sous la direction de son manager avis\u00e9, le Magesi FC utilise g\u00e9n\u00e9ralement une formation 4-4-2 disciplin\u00e9e et organis\u00e9e. L&#039;accent mis sur la solidit\u00e9 d\u00e9fensive et les transitions rapides vers l&#039;attaque lui permet de frustrer les adversaires et de capitaliser sur les opportunit\u00e9s de contre-attaque. Avec un m\u00e9lange de v\u00e9t\u00e9rans chevronn\u00e9s et de jeunes prometteurs, le style de jeu du Magesi FC se caract\u00e9rise par sa r\u00e9silience et sa finesse tactique.<\/p>\n\n\n\n<p>Sekhukhune United, de son c\u00f4t\u00e9, privil\u00e9gie une formation 4-3-3 plus ax\u00e9e sur la possession et l&#039;attaque. L&#039;accent mis sur la r\u00e9tention du ballon et les combinaisons de passes complexes leur permet de contr\u00f4ler le rythme du jeu et de cr\u00e9er des occasions de but. Men\u00e9 par un capitaine inspirant et un noyau de joueurs talentueux, le style de jeu de Sekhukhune United t\u00e9moigne de son ambition et de son d\u00e9sir de pratiquer un football attrayant et offensif.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Formations et acteurs cl\u00e9s : les architectes du jeu<\/strong><\/h3>\n\n\n\n<p>La formation 4-4-2 du Magesi FC offre une structure d\u00e9fensive solide tout en permettant des transitions rapides vers l&#039;attaque. Les deux bancs de quatre, constitu\u00e9s des quatre d\u00e9fenseurs et des quatre milieux de terrain, travaillent \u00e0 l&#039;unisson pour \u00e9touffer les attaques de l&#039;adversaire et lancer des contre-attaques. Les deux attaquants, souvent une combinaison d&#039;un homme cible et d&#039;un braconnier, constituent une menace constante pour la d\u00e9fense adverse.<\/p>\n\n\n\n<p>Le syst\u00e8me 4-3-3 de Sekhukhune United repose sur la cr\u00e9ativit\u00e9 et la mobilit\u00e9 de son trio de milieux de terrain. Les trois milieux de terrain, souvent un m\u00e9lange d&#039;un meneur de jeu en retrait et de deux milieux de terrain box-to-box, dictent le rythme du jeu et cr\u00e9ent des opportunit\u00e9s pour les trois attaquants. Les attaquants lat\u00e9raux, avec leurs talents de dribbleurs et leur capacit\u00e9 \u00e0 couper vers l&#039;int\u00e9rieur, ajoutent une autre dimension au jeu offensif de Sekhukhune United.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Histoire et meilleurs buteurs de tous les temps : un h\u00e9ritage en devenir<\/strong><\/h3>\n\n\n\n<p>Bien que le Magesi FC et le Sekhukhune United soient des clubs relativement jeunes, ils se forgent d\u00e9j\u00e0 une place unique dans le football sud-africain. Leurs meilleurs buteurs de tous les temps, symboles de l&#039;ambition et du potentiel de leurs clubs respectifs, sont v\u00e9n\u00e9r\u00e9s par les fans pour leurs contributions sur le terrain. Au fur et \u00e0 mesure que ces clubs continueront de grandir et d&#039;\u00e9voluer, de nouveaux h\u00e9ros \u00e9mergeront, gravant leurs noms dans les annales de leur histoire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Joueurs \u00e0 surveiller : \u00e9toiles \u00e9mergentes et v\u00e9t\u00e9rans chevronn\u00e9s<\/strong><\/h3>\n\n\n\n<p>Alors que les deux \u00e9quipes se pr\u00e9parent \u00e0 s&#039;affronter, plusieurs joueurs sont sur le point de jouer un r\u00f4le essentiel dans l&#039;issue du match. Le capitaine exp\u00e9riment\u00e9 du Magesi FC, un milieu de terrain aux qualit\u00e9s de leader exceptionnelles, sera le c\u0153ur de leur \u00e9quipe. Le dynamique milieu offensif de Sekhukhune United, avec sa vision du jeu et sa capacit\u00e9 de passe, sera l&#039;orchestrateur de leurs attaques. Les batailles individuelles entre ces joueurs cl\u00e9s, ainsi que les performances d&#039;autres talents \u00e9mergents des deux c\u00f4t\u00e9s, pourraient tr\u00e8s bien d\u00e9terminer le sort du match.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Historique des transferts actuels : construire le succ\u00e8s<\/strong><\/h3>\n\n\n\n<p>Le Magesi FC et le Sekhukhune United ont tous deux \u00e9t\u00e9 actifs sur le march\u00e9 des transferts, dans le but de renforcer leurs effectifs pour les d\u00e9fis \u00e0 venir. Le Magesi FC s&#039;est concentr\u00e9 sur l&#039;acquisition de joueurs qui correspondent \u00e0 sa philosophie tactique et peuvent ajouter de la profondeur \u00e0 son \u00e9quipe. Le Sekhukhune United, d&#039;autre part, a fait des recrutements strat\u00e9giques pour renforcer ses options d&#039;attaque et consolider sa d\u00e9fense. Les activit\u00e9s de transfert des deux clubs refl\u00e8tent leur ambition et leur d\u00e9termination \u00e0 r\u00e9ussir dans le Motsepe Foundation Championship.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusion : Un spectacle digne du championnat de la Fondation Motsepe vous attend<\/strong><\/h2>\n\n\n\n<p>Le choc entre le Magesi FC et le Sekhukhune United promet d&#039;\u00eatre un spectacle digne du Motsepe Foundation Championship, une comp\u00e9tition entre deux \u00e9quipes aux styles, ambitions et philosophies contrast\u00e9s. Le Magesi FC, avec son approche disciplin\u00e9e et ses prouesses en contre-attaque, cherchera \u00e0 frustrer ses adversaires et \u00e0 capitaliser sur toute erreur d\u00e9fensive. Le Sekhukhune United, avec son style ax\u00e9 sur la possession et son intention offensive, cherchera \u00e0 dominer le jeu et \u00e0 imposer sa volont\u00e9 \u00e0 ses adversaires.<\/p>\n\n\n\n<p>Cette rencontre n\u2019est pas seulement un match de football, c\u2019est un t\u00e9moignage de la passion, de la r\u00e9silience et de l\u2019esprit de comp\u00e9tition in\u00e9branlable qui caract\u00e9risent le football sud-africain. C\u2019est une vitrine pour les talents \u00e9mergents, une bataille de g\u00e9nies tactiques et une c\u00e9l\u00e9bration du beau jeu. Alors que les deux \u00e9quipes se pr\u00e9parent \u00e0 s\u2019affronter, la communaut\u00e9 du football attend avec impatience un match rempli d\u2019excitation, de drame et de moments inoubliables.<\/p>\n\n\n\n<p>Le coup de sifflet final marquera la fin de quatre-vingt-dix minutes d\u2019une comp\u00e9tition intense, mais l\u2019impact de ce match r\u00e9sonnera bien au-del\u00e0 des limites du stade. Ce sera l\u2019histoire de r\u00eaves poursuivis, de d\u00e9fis surmont\u00e9s et d\u2019une croyance in\u00e9branlable dans le pouvoir de l\u2019esprit humain. Alors, rassemblons-nous, c\u00e9l\u00e9brons le beau jeu et assistons au d\u00e9roulement de cette rencontre captivante, alors que le Magesi FC et le Sekhukhune United ajoutent un nouveau chapitre \u00e0 leurs parcours footballistiques respectifs.<\/p>","protected":false},"excerpt":{"rendered":"<p>In the heart of South African football, a captivating narrative is set to unfold as Magesi FC prepares to face off against Sekhukhune United in a Motsepe Foundation Championship encounter that embodies the essence of the sport \u2013 passion, resilience, and the unwavering pursuit of victory. Both teams, fueled by their distinct aspirations, are poised [&hellip;]<\/p>","protected":false},"author":1,"featured_media":8655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-8654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Magesi FC vs Sekhukhune United - Lineups - H2H - Livescore - Kickbol<\/title>\n<meta name=\"description\" content=\"Get the inside edge on the Magesi vs Cape Town City game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/fr\/magesi-fc-vs-sekhukhune-united\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magesi FC vs Sekhukhune United - Lineups - H2H - Livescore - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Get the inside edge on the Magesi vs Cape Town City game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/fr\/magesi-fc-vs-sekhukhune-united\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-10T13:11:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-10T13:11:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/MA-vs-SK.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Magesi FC vs Sekhukhune United\",\"datePublished\":\"2024-11-10T13:11:49+00:00\",\"dateModified\":\"2024-11-10T13:11:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/\"},\"wordCount\":890,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MA-vs-SK.png\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/\",\"name\":\"Magesi FC vs Sekhukhune United - Lineups - H2H - Livescore - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MA-vs-SK.png\",\"datePublished\":\"2024-11-10T13:11:49+00:00\",\"dateModified\":\"2024-11-10T13:11:50+00:00\",\"description\":\"Get the inside edge on the Magesi vs Cape Town City game with live scores and in-depth analysis you won't find anywhere else.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MA-vs-SK.png\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MA-vs-SK.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/magesi-fc-vs-sekhukhune-united\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magesi FC vs Sekhukhune United\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/fr\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magesi FC vs Sekhukhune United - Lineups - H2H - Livescore - Kickbol","description":"Get the inside edge on the Magesi vs Cape Town City game with live scores and in-depth analysis you won't find anywhere else.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/fr\/magesi-fc-vs-sekhukhune-united\/","og_locale":"fr_FR","og_type":"article","og_title":"Magesi FC vs Sekhukhune United - Lineups - H2H - Livescore - Kickbol","og_description":"Get the inside edge on the Magesi vs Cape Town City game with live scores and in-depth analysis you won't find anywhere else.","og_url":"https:\/\/kickbol.com\/fr\/magesi-fc-vs-sekhukhune-united\/","og_site_name":"Kickbol","article_published_time":"2024-11-10T13:11:49+00:00","article_modified_time":"2024-11-10T13:11:50+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/MA-vs-SK.png","type":"image\/png"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julius","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Magesi FC vs Sekhukhune United","datePublished":"2024-11-10T13:11:49+00:00","dateModified":"2024-11-10T13:11:50+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/"},"wordCount":890,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/MA-vs-SK.png","articleSection":["Head to Head"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/","url":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/","name":"Magesi FC vs Sekhukhune United - Lineups - H2H - Livescore - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/MA-vs-SK.png","datePublished":"2024-11-10T13:11:49+00:00","dateModified":"2024-11-10T13:11:50+00:00","description":"Get the inside edge on the Magesi vs Cape Town City game with live scores and in-depth analysis you won't find anywhere else.","breadcrumb":{"@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/MA-vs-SK.png","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/MA-vs-SK.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/magesi-fc-vs-sekhukhune-united\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Magesi FC vs Sekhukhune United"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/fr\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/8654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/comments?post=8654"}],"version-history":[{"count":1,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/8654\/revisions"}],"predecessor-version":[{"id":8656,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/8654\/revisions\/8656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/media\/8655"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/media?parent=8654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/categories?post=8654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/tags?post=8654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}