{"id":8225,"date":"2024-09-27T19:28:23","date_gmt":"2024-09-27T19:28:23","guid":{"rendered":"https:\/\/kickbol.com\/?p=8225"},"modified":"2024-09-27T19:28:24","modified_gmt":"2024-09-27T19:28:24","slug":"union-berlin-vs-fc-st-paul","status":"publish","type":"post","link":"https:\/\/kickbol.com\/fr\/union-berlin-vs-fc-st-paul\/","title":{"rendered":"Union Berlin contre FC St. Paul"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM --><div id=\"ls-widget\" data-w=\"w_custom\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/germany\/st-pauli-union-berlin\/1861186?w=w_custom\" class=\"livescore-widget\"><\/div><script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script><!-- LIVESCORE WIDGET SOCCERSAPI.COM -->\n\n\n\n<p>Au c\u0153ur du football allemand, o\u00f9 le courage et la passion se m\u00ealent \u00e0 l&#039;\u00e9clat tactique, se trouve un \u00e9l\u00e9ment qui incarne l&#039;essence m\u00eame du football. <a href=\"https:\/\/kickbol.com\/fr\/bundesliga\/\">Bundesliga<\/a>:Union Berlin contre FC St. Pauli. Ce n&#039;est pas seulement un affrontement entre deux \u00e9quipes, c&#039;est une collision de styles contrast\u00e9s, un t\u00e9moignage de la richesse de la culture footballistique allemande et un spectacle qui promet de passionner les fans du premier au dernier coup de sifflet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Face \u00e0 face : une rivalit\u00e9 charg\u00e9e d&#039;histoire<\/strong><\/h3>\n\n\n\n<p>L&#039;histoire entre l&#039;Union Berlin et le FC St. Pauli est un r\u00e9cit fascinant de r\u00e9silience, d&#039;ambition et de soutien ind\u00e9fectible. Ces deux clubs se sont affront\u00e9s \u00e0 de nombreuses reprises, leurs rencontres marquant des moments inoubliables dans les annales du football allemand. Des batailles acharn\u00e9es dans les divisions inf\u00e9rieures aux affrontements captivants en Bundesliga, cette rencontre a toujours \u00e9t\u00e9 une d\u00e9monstration de drame, d&#039;excitation et de beaut\u00e9 du jeu.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Statistique<\/th><th>Union Berlin<\/th><th>FC St. Pauli<\/th><\/tr><\/thead><tbody><tr><td>Victoires<\/td><td>5<\/td><td>3<\/td><\/tr><tr><td>Pertes<\/td><td>3<\/td><td>5<\/td><\/tr><tr><td>Tirages au sort<\/td><td>2<\/td><td>2<\/td><\/tr><tr><td>Buts marqu\u00e9s<\/td><td>16<\/td><td>14<\/td><\/tr><tr><td>Buts encaiss\u00e9s<\/td><td>14<\/td><td>16<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Masterclass tactique : un contraste de styles<\/strong><\/p>\n\n\n\n<p>Sous la direction avis\u00e9e de son manager, l&#039;Union Berlin s&#039;est forg\u00e9 une r\u00e9putation de discipline et d&#039;organisation. Son syst\u00e8me 3-5-2 privil\u00e9gi\u00e9 offre une base d\u00e9fensive solide tout en permettant des transitions rapides vers l&#039;attaque. Les lat\u00e9raux offrent de la largeur et de l&#039;\u00e9lan offensif, tandis que les trois d\u00e9fenseurs centraux constituent une formidable barri\u00e8re pour les attaquants adverses. Le style de jeu de l&#039;Union t\u00e9moigne de son \u00e9thique de travail in\u00e9branlable et de sa capacit\u00e9 \u00e0 ex\u00e9cuter son plan de jeu avec pr\u00e9cision.<\/p>\n\n\n\n<p>Le FC St. Pauli, en revanche, incarne un style de football plus fluide et expressif. Sa formation en 4-3-3 permet une cr\u00e9ativit\u00e9 et un sens de l&#039;attaque, le trio du milieu de terrain dictant le rythme du jeu et les trois attaquants constituant une menace constante pour la d\u00e9fense adverse. La philosophie du FC St. Pauli repose sur sa croyance dans le football offensif et son d\u00e9sir de divertir les supporters avec son style de jeu.<\/p>\n\n\n\n<p><strong>Formations et acteurs cl\u00e9s : les architectes du jeu<\/strong><\/p>\n\n\n\n<p>Le syst\u00e8me 3-5-2 de l&#039;Union Berlin permet une flexibilit\u00e9 et une adaptabilit\u00e9 tactiques. Les lat\u00e9raux, avec leur capacit\u00e9 \u00e0 courir et \u00e0 centrer sans rel\u00e2che, sont essentiels pour cr\u00e9er des occasions de but. Le trio du milieu de terrain offre un \u00e9quilibre entre solidit\u00e9 d\u00e9fensive et cr\u00e9ativit\u00e9 offensive. Les deux attaquants, souvent une combinaison d&#039;un d\u00e9fenseur central et d&#039;un buteur, offrent une vari\u00e9t\u00e9 d&#039;options offensives.<\/p>\n\n\n\n<p>Le syst\u00e8me 4-3-3 de St. Pauli repose sur la fluidit\u00e9 et la mobilit\u00e9 de ses joueurs. Le trio du milieu de terrain, avec sa capacit\u00e9 de passe et sa vision du jeu, est le chef d&#039;orchestre des attaques de l&#039;\u00e9quipe. Les attaquants, avec leur vitesse et leur ruse, \u00e9tirent la d\u00e9fense adverse et cr\u00e9ent des espaces pour l&#039;attaquant central. L&#039;attaquant solitaire, souvent un finisseur clinique, est charg\u00e9 de transformer les occasions de l&#039;\u00e9quipe en buts.<\/p>\n\n\n\n<p><strong>Histoire et meilleurs buteurs de tous les temps : des l\u00e9gendes grav\u00e9es dans l&#039;or<\/strong><\/p>\n\n\n\n<p>L&#039;Union Berlin, avec son pass\u00e9 historique, peut se targuer d&#039;une riche tradition dans le football allemand. Son meilleur buteur de tous les temps, une ic\u00f4ne du club, est v\u00e9n\u00e9r\u00e9 par les fans pour ses exploits prolifiques en mati\u00e8re de buts et sa loyaut\u00e9 ind\u00e9fectible envers le club. Le FC St. Pauli, avec son identit\u00e9 unique et sa base de fans passionn\u00e9s, a \u00e9galement produit son lot de h\u00e9ros buteurs. Son meilleur buteur de tous les temps, une figure culte parmi les fans, est connu pour ses buts m\u00e9morables et son incarnation de l&#039;esprit du club.<\/p>\n\n\n\n<p><strong>Les joueurs \u00e0 surveiller : les \u00e9toiles montantes et les v\u00e9t\u00e9rans chevronn\u00e9s<\/strong><\/p>\n\n\n\n<p>Alors que les deux \u00e9quipes se pr\u00e9parent \u00e0 affronter, plusieurs joueurs sont sur le point de jouer un r\u00f4le cl\u00e9 dans l&#039;issue du match. Le capitaine de l&#039;Union Berlin, un v\u00e9t\u00e9ran de la campagne avec une grande exp\u00e9rience, sera un \u00e9l\u00e9ment cl\u00e9 dans l&#039;organisation de la d\u00e9fense et dans la direction de l&#039;exemple. Le milieu de terrain dynamique de St. Pauli, avec sa cr\u00e9ativit\u00e9 et sa capacit\u00e9 de passe, sera la cl\u00e9 pour d\u00e9bloquer la d\u00e9fense de l&#039;Union. Les batailles individuelles entre ces joueurs cl\u00e9s pourraient tr\u00e8s bien d\u00e9terminer le sort du match.<\/p>\n\n\n\n<p><strong>Historique des transferts actuels : construire l&#039;avenir<\/strong><\/p>\n\n\n\n<p>L&#039;Union Berlin et le FC St. Pauli ont tous deux \u00e9t\u00e9 actifs sur le march\u00e9 des transferts, dans le but de renforcer leurs effectifs pour les d\u00e9fis \u00e0 venir. L&#039;Union s&#039;est concentr\u00e9e sur l&#039;acquisition de joueurs qui correspondent \u00e0 son syst\u00e8me tactique et peuvent contribuer \u00e0 l&#039;effort collectif. Le St. Pauli a cherch\u00e9 \u00e0 ajouter de la cr\u00e9ativit\u00e9 et du flair offensif \u00e0 ses rangs, tout en renfor\u00e7ant ses options d\u00e9fensives. Les activit\u00e9s de transfert des deux clubs refl\u00e8tent leur ambition et leur d\u00e9sir de concourir au plus haut niveau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusion : Un spectacle de Bundesliga nous attend<\/strong><\/h2>\n\n\n\n<p>Le choc entre l&#039;Union Berlin et le FC St. Pauli est plus qu&#039;un simple match de football ; c&#039;est une c\u00e9l\u00e9bration de la riche palette de ce sport, un t\u00e9moignage de la passion et de la loyaut\u00e9 des fans, et une vitrine des styles contrast\u00e9s qui rendent la Bundesliga si captivante.<\/p>\n\n\n\n<p>L&#039;Union Berlin, avec son approche disciplin\u00e9e et organis\u00e9e, cherchera \u00e0 contrecarrer les intentions offensives de St. Pauli et \u00e0 capitaliser sur ses propres opportunit\u00e9s. St. Pauli, avec son style fluide et expressif, cherchera \u00e0 briser la d\u00e9fense de l&#039;Union et \u00e0 divertir les supporters avec ses prouesses offensives.<\/p>\n\n\n\n<p>Cette rencontre promet d&#039;\u00eatre une le\u00e7on de tactique magistrale, une bataille de volont\u00e9s et un spectacle qui laissera une trace durable \u00e0 tous ceux qui y assisteront. Le coup de sifflet final marquera la fin de quatre-vingt-dix minutes de comp\u00e9tition intense, mais les souvenirs de ce match resteront grav\u00e9s dans les c\u0153urs et les esprits des supporters pendant des ann\u00e9es.<\/p>\n\n\n\n<p>Alors, plongeons-nous dans l&#039;ambiance, partageons la passion et savourons chaque instant de ce classique de la Bundesliga. Alors que l&#039;Union Berlin et le FC St. Pauli entrent sur le terrain, c\u00e9l\u00e9brons le beau jeu et l&#039;esprit de comp\u00e9tition in\u00e9branlable qui le caract\u00e9rise. Que la meilleure \u00e9quipe gagne et que les fans puissent assister \u00e0 un spectacle digne de leur soutien ind\u00e9fectible.<\/p>","protected":false},"excerpt":{"rendered":"<p>In the heart of German football, where grit and passion intertwine with tactical brilliance, lies a fixture that embodies the essence of the Bundesliga: Union Berlin vs FC St. Pauli. This isn&#8217;t merely a clash between two teams; it&#8217;s a collision of contrasting styles, a testament to the rich tapestry of German football culture, and [&hellip;]<\/p>","protected":false},"author":1,"featured_media":8226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-8225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Union Berlin vs FC St. Paul - Kickbol<\/title>\n<meta name=\"description\" content=\"Get the inside edge on the Union Berlin vs FC St. Pauli game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/fr\/union-berlin-vs-fc-st-paul\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Union Berlin vs FC St. Paul - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Get the inside edge on the Union Berlin vs FC St. Pauli game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/fr\/union-berlin-vs-fc-st-paul\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T19:28:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T19:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-pauli.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Union Berlin vs FC St. Paul\",\"datePublished\":\"2024-09-27T19:28:23+00:00\",\"dateModified\":\"2024-09-27T19:28:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/\"},\"wordCount\":952,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-pauli.png\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/\",\"name\":\"Union Berlin vs FC St. Paul - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-pauli.png\",\"datePublished\":\"2024-09-27T19:28:23+00:00\",\"dateModified\":\"2024-09-27T19:28:24+00:00\",\"description\":\"Get the inside edge on the Union Berlin vs FC St. Pauli game with live scores and in-depth analysis you won't find anywhere else.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-pauli.png\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-pauli.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-fc-st-paul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Union Berlin vs FC St. Paul\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/fr\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Union Berlin vs FC St. Paul - Kickbol","description":"Get the inside edge on the Union Berlin vs FC St. Pauli game with live scores and in-depth analysis you won't find anywhere else.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/fr\/union-berlin-vs-fc-st-paul\/","og_locale":"fr_FR","og_type":"article","og_title":"Union Berlin vs FC St. Paul - Kickbol","og_description":"Get the inside edge on the Union Berlin vs FC St. Pauli game with live scores and in-depth analysis you won't find anywhere else.","og_url":"https:\/\/kickbol.com\/fr\/union-berlin-vs-fc-st-paul\/","og_site_name":"Kickbol","article_published_time":"2024-09-27T19:28:23+00:00","article_modified_time":"2024-09-27T19:28:24+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-pauli.png","type":"image\/png"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julius","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Union Berlin vs FC St. Paul","datePublished":"2024-09-27T19:28:23+00:00","dateModified":"2024-09-27T19:28:24+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/"},"wordCount":952,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-pauli.png","articleSection":["Head to Head"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/","url":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/","name":"Union Berlin vs FC St. Paul - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-pauli.png","datePublished":"2024-09-27T19:28:23+00:00","dateModified":"2024-09-27T19:28:24+00:00","description":"Get the inside edge on the Union Berlin vs FC St. Pauli game with live scores and in-depth analysis you won't find anywhere else.","breadcrumb":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-pauli.png","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-pauli.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/union-berlin-vs-fc-st-paul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Union Berlin vs FC St. Paul"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/fr\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/8225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/comments?post=8225"}],"version-history":[{"count":1,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/8225\/revisions"}],"predecessor-version":[{"id":8227,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/8225\/revisions\/8227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/media\/8226"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/media?parent=8225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/categories?post=8225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/tags?post=8225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}