{"id":1588,"date":"2023-11-23T19:42:31","date_gmt":"2023-11-23T19:42:31","guid":{"rendered":"https:\/\/kickbol.com\/?p=1588"},"modified":"2024-06-19T15:41:15","modified_gmt":"2024-06-19T15:41:15","slug":"arsenal-vs-chelsea-a-premier-league-classic","status":"publish","type":"post","link":"https:\/\/kickbol.com\/fr\/arsenal-vs-chelsea-a-premier-league-classic\/","title":{"rendered":"Arsenal contre Chelsea"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM --><div id=\"ls-widget\" data-w=\"w_custom\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/england\/arsenal-fc-chelsea-fc\/1811734?w=w_custom\" class=\"livescore-widget\"><\/div><script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script><!-- LIVESCORE WIDGET SOCCERSAPI.COM -->\n\n\n\n<p>Arsenal et Chelsea sont deux des clubs les plus titr\u00e9s et les plus c\u00e9l\u00e8bres de l&#039;histoire du football anglais, avec un total cumul\u00e9 de 31 titres de Premier League, 14 FA Cups et 18 League Cups. Leur rivalit\u00e9, qui dure depuis plus d&#039;un si\u00e8cle, a donn\u00e9 lieu \u00e0 d&#039;innombrables matchs m\u00e9morables, \u00e0 des moments embl\u00e9matiques et \u00e0 une histoire commune de succ\u00e8s.<\/p>\n\n\n\n<p><strong>Bilan face \u00e0 face<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Concours<\/th><th>Victoires d&#039;Arsenal<\/th><th>Victoire de Chelsea<\/th><th>Tirages au sort<\/th><th>Buts pour (Arsenal)<\/th><th>Buts pour (Chelsea)<\/th><\/tr><\/thead><tbody><tr><td>Toutes les comp\u00e9titions<\/td><td>85<\/td><td>89<\/td><td>43<\/td><td>287<\/td><td>284<\/td><\/tr><tr><td>Premier League<\/td><td>35<\/td><td>33<\/td><td>24<\/td><td>113<\/td><td>99<\/td><\/tr><tr><td>Coupe d&#039;Angleterre<\/td><td>14<\/td><td>13<\/td><td>12<\/td><td>41<\/td><td>38<\/td><\/tr><tr><td>Coupe de la Ligue<\/td><td>6<\/td><td>5<\/td><td>3<\/td><td>18<\/td><td>14<\/td><\/tr><tr><td>Ligue des Champions de l&#039;UEFA<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>5<\/td><td>5<\/td><\/tr><tr><td>Ligue Europa de l&#039;UEFA<\/td><td>1<\/td><td>0<\/td><td>0<\/td><td>5<\/td><td>2<\/td><\/tr><tr><td>Super Coupe de l&#039;UEFA<\/td><td>1<\/td><td>0<\/td><td>0<\/td><td>1<\/td><td>0<\/td><\/tr><tr><td>Autre<\/td><td>17<\/td><td>20<\/td><td>13<\/td><td>91<\/td><td>96<\/td><\/tr><tr><td>Total<\/td><td>156<\/td><td>161<\/td><td>96<\/td><td>471<\/td><td>438<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Rencontres r\u00e9centes<\/strong><\/p>\n\n\n\n<p>Au cours des derni\u00e8res saisons, Arsenal et Chelsea ont continu\u00e9 \u00e0 produire des matchs passionnants, chacun mettant en valeur ses prouesses offensives et son sens tactique. La saison 2022-23 a vu quatre confrontations entre les deux \u00e9quipes, Chelsea remportant trois matchs et Arsenal un. Ces matchs ont mis en \u00e9vidence l&#039;intensit\u00e9 de la rivalit\u00e9 et la pers\u00e9v\u00e9rance des deux \u00e9quipes.<\/p>\n\n\n\n<p><strong>Facteurs cl\u00e9s et dynamique de rivalit\u00e9<\/strong><\/p>\n\n\n\n<p>Plusieurs facteurs ont aliment\u00e9 la rivalit\u00e9 durable entre Arsenal et Chelsea :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Proximit\u00e9 g\u00e9ographique :<\/strong> Situ\u00e9s \u00e0 quelques kilom\u00e8tres l&#039;un de l&#039;autre \u00e0 Londres, les deux clubs entretiennent une rivalit\u00e9 g\u00e9ographique naturelle.<\/li>\n\n\n\n<li><strong>Histoire partag\u00e9e :<\/strong> Les deux clubs ont une riche histoire de succ\u00e8s, avec un total combin\u00e9 de 31 titres de Premier League et de nombreux troph\u00e9es nationaux et europ\u00e9ens.<\/li>\n\n\n\n<li><strong>Styles de jeu contrast\u00e9s :<\/strong> Arsenal est traditionnellement connu pour son sens de l&#039;attaque et son jeu cr\u00e9atif, tandis que Chelsea a \u00e9t\u00e9 plus r\u00e9solu d\u00e9fensivement et plus disciplin\u00e9 tactiquement.<\/li>\n\n\n\n<li><strong>Rivalit\u00e9 de gestion :<\/strong> La rivalit\u00e9 a \u00e9galement \u00e9t\u00e9 intensifi\u00e9e par les personnalit\u00e9s et les styles de gestion d&#039;Ars\u00e8ne Wenger et de Jos\u00e9 Mourinho, qui se sont affront\u00e9s \u00e0 de nombreuses reprises.<\/li>\n\n\n\n<li><strong>Rivalit\u00e9 entre les fans :<\/strong> La rivalit\u00e9 entre Arsenal et Chelsea se refl\u00e8te \u00e9galement dans leurs supporters passionn\u00e9s, qui cr\u00e9ent une atmosph\u00e8re hostile et \u00e9lectrisante lors de leurs rencontres.<\/li>\n<\/ul>\n\n\n\n<p><strong>Impact sur le football anglais<\/strong><\/p>\n\n\n\n<p>La rivalit\u00e9 entre Arsenal et Chelsea a eu un impact significatif sur le football anglais :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00c9lever le niveau de jeu :<\/strong> Leur qu\u00eate constante des plus grands honneurs a forc\u00e9 d\u2019autres clubs \u00e0 \u00e9lever leur niveau de jeu, contribuant ainsi \u00e0 l\u2019am\u00e9lioration g\u00e9n\u00e9rale du niveau de jeu en Premier League.<\/li>\n\n\n\n<li><strong>Appel mondial :<\/strong> Leurs matchs figurent r\u00e9guli\u00e8rement parmi les rencontres les plus regard\u00e9es de la Premier League, attirant des millions de t\u00e9l\u00e9spectateurs dans le monde entier.<\/li>\n\n\n\n<li><strong>Marketing et image de marque :<\/strong> La rivalit\u00e9 a \u00e9galement contribu\u00e9 \u00e0 la croissance de la marque Premier League et \u00e0 sa popularit\u00e9 dans le monde entier.<\/li>\n<\/ul>\n\n\n\n<p><strong>Conclusion<\/strong><\/p>\n\n\n\n<p>Arsenal vs Chelsea est une rivalit\u00e9 qui transcende le terrain de football. C&#039;est un choc de styles, une bataille pour la supr\u00e9matie et un test de volont\u00e9 entre deux des clubs les plus titr\u00e9s d&#039;Angleterre. Leur histoire est \u00e9troitement li\u00e9e, leur rivalit\u00e9 est f\u00e9rocement disput\u00e9e et leurs rencontres futures promettent d&#039;offrir plus de drame, d&#039;excitation et de moments inoubliables.<\/p>","protected":false},"excerpt":{"rendered":"<p>Arsenal et Chelsea sont deux des clubs les plus titr\u00e9s et les plus c\u00e9l\u00e8bres de l\u2019histoire du football anglais, avec un total combin\u00e9 de 31 titres de Premier League, 14 FA Cups et 18 League Cups. Leur rivalit\u00e9, qui dure depuis plus d\u2019un si\u00e8cle, a donn\u00e9 lieu \u00e0 d\u2019innombrables matchs m\u00e9morables, \u00e0 des moments embl\u00e9matiques et \u00e0 une histoire commune de succ\u00e8s. Comp\u00e9tition de records en face \u00e0 face Arsenal remporte [\u2026]<\/p>","protected":false},"author":1,"featured_media":1615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-1588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arsenal vs Chelsea - Kickbol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/fr\/arsenal-vs-chelsea-a-premier-league-classic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arsenal vs Chelsea - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Arsenal and Chelsea stand as two of the most successful and storied clubs in English football history, with a combined 31 Premier League titles, 14 FA Cups, and 18 League Cups. Their rivalry, spanning over a century, has produced countless memorable matches, iconic moments, and a shared history of success. Head-to-Head Record Competition Arsenal Wins [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/fr\/arsenal-vs-chelsea-a-premier-league-classic\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T19:42:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T15:41:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/ars-vs-che.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Arsenal vs Chelsea\",\"datePublished\":\"2023-11-23T19:42:31+00:00\",\"dateModified\":\"2024-06-19T15:41:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ars-vs-che.jpeg\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/\",\"name\":\"Arsenal vs Chelsea - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ars-vs-che.jpeg\",\"datePublished\":\"2023-11-23T19:42:31+00:00\",\"dateModified\":\"2024-06-19T15:41:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ars-vs-che.jpeg\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ars-vs-che.jpeg\",\"width\":230,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/arsenal-vs-chelsea-a-premier-league-classic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arsenal vs Chelsea\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/fr\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arsenal vs Chelsea - Kickbol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/fr\/arsenal-vs-chelsea-a-premier-league-classic\/","og_locale":"fr_FR","og_type":"article","og_title":"Arsenal vs Chelsea - Kickbol","og_description":"Arsenal and Chelsea stand as two of the most successful and storied clubs in English football history, with a combined 31 Premier League titles, 14 FA Cups, and 18 League Cups. Their rivalry, spanning over a century, has produced countless memorable matches, iconic moments, and a shared history of success. Head-to-Head Record Competition Arsenal Wins [&hellip;]","og_url":"https:\/\/kickbol.com\/fr\/arsenal-vs-chelsea-a-premier-league-classic\/","og_site_name":"Kickbol","article_published_time":"2023-11-23T19:42:31+00:00","article_modified_time":"2024-06-19T15:41:15+00:00","og_image":[{"width":230,"height":180,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/ars-vs-che.jpeg","type":"image\/jpeg"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julius","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Arsenal vs Chelsea","datePublished":"2023-11-23T19:42:31+00:00","dateModified":"2024-06-19T15:41:15+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/"},"wordCount":424,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/ars-vs-che.jpeg","articleSection":["Head to Head"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/","url":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/","name":"Arsenal vs Chelsea - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/ars-vs-che.jpeg","datePublished":"2023-11-23T19:42:31+00:00","dateModified":"2024-06-19T15:41:15+00:00","breadcrumb":{"@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/ars-vs-che.jpeg","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/ars-vs-che.jpeg","width":230,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/arsenal-vs-chelsea-a-premier-league-classic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Arsenal vs Chelsea"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/fr\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/1588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/comments?post=1588"}],"version-history":[{"count":4,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/1588\/revisions"}],"predecessor-version":[{"id":5303,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/posts\/1588\/revisions\/5303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/media\/1615"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/media?parent=1588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/categories?post=1588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/fr\/wp-json\/wp\/v2\/tags?post=1588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}