{"id":8219,"date":"2024-09-27T19:11:08","date_gmt":"2024-09-27T19:11:08","guid":{"rendered":"https:\/\/kickbol.com\/?p=8219"},"modified":"2024-09-27T19:11:09","modified_gmt":"2024-09-27T19:11:09","slug":"union-berlin-vs-mainz","status":"publish","type":"post","link":"https:\/\/kickbol.com\/es\/union-berlin-vs-mainz\/","title":{"rendered":"Uni\u00f3n Berl\u00edn vs Maguncia"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM --><div id=\"ls-widget\" data-w=\"w_custom\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/germany\/union-berlin-mainz\/1861175?w=w_custom\" class=\"livescore-widget\"><\/div><script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script><!-- LIVESCORE WIDGET SOCCERSAPI.COM -->\n\n\n\n<p>Como el <a href=\"https:\/\/kickbol.com\/es\/bundesliga\/\">Bundesliga<\/a> A medida que avance la temporada, el choque entre el Union Berlin y el Mainz 05 se perfila como un encuentro apasionante que pondr\u00e1 de relieve los estilos y ambiciones contrastantes de estos dos clubes. El Union Berlin, con su ascenso mete\u00f3rico y su determinaci\u00f3n inquebrantable, aspira a consolidar su posici\u00f3n entre la \u00e9lite de la Bundesliga. El Mainz, con su rica historia y astucia t\u00e1ctica, busca recuperar su lugar en los escalones superiores del f\u00fatbol alem\u00e1n. Este encuentro trasciende las meras estad\u00edsticas; encarna el esp\u00edritu de competencia, resiliencia y b\u00fasqueda de la excelencia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cara a cara: un tira y afloja entre goles y gloria<\/strong><\/h3>\n\n\n\n<p>Hist\u00f3ricamente, los encuentros entre el Union Berlin y el Mainz han sido encuentros muy disputados, sin que ninguno de los dos equipos haya logrado un dominio claro. Las estad\u00edsticas de los enfrentamientos directos muestran una rivalidad equilibrada, en la que cada gol, cada pase y cada entrada est\u00e1n impregnados de importancia.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Estad\u00edstica<\/th><th>Uni\u00f3n Berl\u00edn<\/th><th>Maguncia 05<\/th><\/tr><\/thead><tbody><tr><td>Victorias<\/td><td>3<\/td><td>4<\/td><\/tr><tr><td>P\u00e9rdidas<\/td><td>4<\/td><td>3<\/td><\/tr><tr><td>Sorteos<\/td><td>2<\/td><td>2<\/td><\/tr><tr><td>Goles marcados<\/td><td>12<\/td><td>15<\/td><\/tr><tr><td>Goles recibidos<\/td><td>15<\/td><td>12<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Estos n\u00fameros cuentan la historia de dos equipos muy igualados, cada uno capaz de causarle problemas al otro. El pr\u00f3ximo partido promete ser otro cap\u00edtulo de esta apasionante historia, donde los m\u00e1rgenes entre la victoria y la derrota son muy estrechos.<\/p>\n\n\n\n<p><strong>Tira y afloja t\u00e1ctico: estilos de juego contrastantes<\/strong><\/p>\n\n\n\n<p>El Union Berlin, conocido por su esp\u00edritu colectivo y su disciplina, suele emplear una formaci\u00f3n 3-5-2. Este sistema le permite mantener una formaci\u00f3n defensiva compacta y, al mismo tiempo, ofrecer flexibilidad en el ataque. Su \u00e9nfasis en las transiciones r\u00e1pidas, la destreza en las jugadas a bal\u00f3n parado y la presi\u00f3n incesante han demostrado ser una combinaci\u00f3n potente en la Bundesliga. Liderados por su inspirador capit\u00e1n y un n\u00facleo de jugadores comprometidos, el estilo de juego del Union Berlin encarna la esencia del trabajo en equipo y la resiliencia.<\/p>\n\n\n\n<p>El Mainz, bajo la astuta direcci\u00f3n de su entrenador, prefiere un planteamiento basado m\u00e1s en la posesi\u00f3n, desplegando a menudo una formaci\u00f3n 4-2-3-1. Su \u00e9nfasis en la retenci\u00f3n del bal\u00f3n, las combinaciones intrincadas de pases y el juego posicional le permiten controlar el ritmo del juego y crear oportunidades de gol. La flexibilidad t\u00e1ctica del Mainz y su capacidad para adaptarse a diferentes oponentes lo convierten en un desaf\u00edo formidable para cualquier equipo.<\/p>\n\n\n\n<p><strong>Formaciones y actores clave: los arquitectos del \u00e9xito<\/strong><\/p>\n\n\n\n<p>El sistema 3-5-2 del Union Berlin proporciona una base defensiva s\u00f3lida, con tres defensas centrales que ofrecen protecci\u00f3n y los laterales que aportan amplitud al ataque. Los dos centrocampistas centrales tienen la tarea de romper los ataques del rival e iniciar contraataques. El centrocampista ofensivo act\u00faa como eje creativo, mientras que los dos delanteros combinan su movimiento y su capacidad de remate para inquietar a la defensa rival.<\/p>\n\n\n\n<p>El sistema 4-2-3-1 del Mainz le permite controlar el centro del campo y dominar la posesi\u00f3n. Los dos centrocampistas de contenci\u00f3n protegen a la defensa, mientras que el centrocampista ofensivo y los extremos crean oportunidades para el \u00fanico delantero. La fluidez t\u00e1ctica del Mainz y su capacidad para cambiar de formaciones hacen que sea un equipo dif\u00edcil de predecir.<\/p>\n\n\n\n<p><strong>Historia y m\u00e1ximos goleadores de todos los tiempos: un tapiz de goles<\/strong><\/p>\n\n\n\n<p>El Union Berlin, aunque es relativamente nuevo en la Bundesliga, tiene una rica historia arraigada en el barrio obrero de K\u00f6penick. Su m\u00e1ximo goleador de todos los tiempos, una leyenda del club, encarna el esp\u00edritu del club y es venerado por los aficionados por su inquebrantable compromiso y sus prol\u00edficas haza\u00f1as goleadoras.<\/p>\n\n\n\n<p>El Mainz, con su larga presencia en el f\u00fatbol alem\u00e1n, cuenta con una orgullosa historia y un legado de formaci\u00f3n de j\u00f3venes talentos. Su m\u00e1ximo goleador de todos los tiempos, producto de su academia juvenil, ejemplifica el compromiso del club con el desarrollo de jugadores y con brindarles una plataforma para brillar.<\/p>\n\n\n\n<p><strong>Jugadores a seguir: estrellas emergentes y veteranos experimentados<\/strong><\/p>\n\n\n\n<p>Mientras los dos equipos se preparan para el choque, varios jugadores est\u00e1n preparados para desempe\u00f1ar papeles decisivos para determinar el resultado del partido. El capit\u00e1n del Union Berlin, un l\u00edder vocal y maestro del mediocampo, ser\u00e1 fundamental para dictar el ritmo del juego e inspirar a sus compa\u00f1eros de equipo. El creativo mediapunta del Mainz, con su visi\u00f3n y capacidad de pase, ser\u00e1 la clave para desbloquear la defensa del Union Berlin. Las batallas individuales entre estos jugadores clave agregar\u00e1n otra capa de intriga a este cautivador encuentro.<\/p>\n\n\n\n<p><strong>Historial de transferencias actual: construyendo el futuro<\/strong><\/p>\n\n\n\n<p>Tanto el Union Berlin como el Mainz han estado activos en el mercado de fichajes, con el objetivo de reforzar sus plantillas para los retos que se avecinan. El Union Berlin se ha centrado en adquirir jugadores que se adapten a su sistema y representen el esp\u00edritu del club. El Mainz, por su parte, ha buscado a\u00f1adir profundidad y calidad a su plantilla, al tiempo que ofrece oportunidades de desarrollo para los jugadores j\u00f3venes. Las actividades de fichajes de ambos clubes reflejan sus visiones a largo plazo y su inquebrantable compromiso con el \u00e9xito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusi\u00f3n: un choque de la Bundesliga de proporciones \u00e9picas<\/strong><\/h2>\n\n\n\n<p>El encuentro entre el Union Berlin y el Mainz promete ser un choque de proporciones \u00e9picas en la Bundesliga, un duelo entre dos equipos con estilos, ambiciones y filosof\u00edas contrastantes. El Union Berlin, con su esp\u00edritu inquebrantable y su determinaci\u00f3n colectiva, intentar\u00e1 mantener su trayectoria ascendente y desafiar el orden establecido. El Mainz, con su astucia t\u00e1ctica y su planteamiento basado en la posesi\u00f3n, intentar\u00e1 recuperar su lugar entre la \u00e9lite de la Bundesliga.<\/p>\n\n\n\n<p>Este encuentro trasciende las meras estad\u00edsticas; encarna la esencia de la competici\u00f3n, la b\u00fasqueda de la excelencia y la inquebrantable creencia en el poder del trabajo en equipo. Mientras los dos equipos se preparan para enfrentarse, el mundo del f\u00fatbol espera con impaciencia un partido lleno de pasi\u00f3n, dramatismo y momentos inolvidables. El pitido final marcar\u00e1 el final de noventa minutos de intensa competici\u00f3n, pero el impacto de este partido resonar\u00e1 mucho m\u00e1s all\u00e1 de los confines del estadio. Ser\u00e1 una historia de sue\u00f1os perseguidos, de desaf\u00edos superados y del inquebrantable esp\u00edritu de competici\u00f3n que define a la Bundesliga.<\/p>\n\n\n\n<p>As\u00ed pues, sent\u00e9monos, relaj\u00e9monos y disfrutemos de este encuentro fascinante, en el que el Union Berlin y el Mainz escriben otro cap\u00edtulo en sus respectivas trayectorias futbol\u00edsticas. Que gane el mejor equipo, pero, lo que es m\u00e1s importante, que este partido sirva como recordatorio de la belleza de este deporte y del esp\u00edritu indomable de quienes lo practican.<\/p>","protected":false},"excerpt":{"rendered":"<p>A medida que avanza la temporada de la Bundesliga, el choque entre el Union Berlin y el Mainz 05 se perfila como un encuentro apasionante, que pondr\u00e1 de relieve los estilos y ambiciones contrastantes de estos dos clubes. El Union Berlin, con su ascenso mete\u00f3rico y su determinaci\u00f3n inquebrantable, aspira a consolidar su posici\u00f3n entre la \u00e9lite de la Bundesliga. El Mainz, con su rica historia y su [\u2026]<\/p>","protected":false},"author":1,"featured_media":8220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-8219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Union Berlin vs Mainz - Lineups - H2H - Livescore - Kickbol<\/title>\n<meta name=\"description\" content=\"Get the inside edge on the Union Berlin vs Mainz game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/es\/union-berlin-vs-mainz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Union Berlin vs Mainz - Lineups - H2H - Livescore - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Get the inside edge on the Union Berlin vs Mainz game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/es\/union-berlin-vs-mainz\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T19:11:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T19:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-main.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Union Berlin vs Mainz\",\"datePublished\":\"2024-09-27T19:11:08+00:00\",\"dateModified\":\"2024-09-27T19:11:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/\"},\"wordCount\":955,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-main.png\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/\",\"name\":\"Union Berlin vs Mainz - Lineups - H2H - Livescore - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-main.png\",\"datePublished\":\"2024-09-27T19:11:08+00:00\",\"dateModified\":\"2024-09-27T19:11:09+00:00\",\"description\":\"Get the inside edge on the Union Berlin vs Mainz game with live scores and in-depth analysis you won't find anywhere else.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-main.png\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/UB-vs-main.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/union-berlin-vs-mainz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Union Berlin vs Mainz\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/es\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Union Berlin vs Mainz - Lineups - H2H - Livescore - Kickbol","description":"Get the inside edge on the Union Berlin vs Mainz game with live scores and in-depth analysis you won't find anywhere else.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/es\/union-berlin-vs-mainz\/","og_locale":"es_ES","og_type":"article","og_title":"Union Berlin vs Mainz - Lineups - H2H - Livescore - Kickbol","og_description":"Get the inside edge on the Union Berlin vs Mainz game with live scores and in-depth analysis you won't find anywhere else.","og_url":"https:\/\/kickbol.com\/es\/union-berlin-vs-mainz\/","og_site_name":"Kickbol","article_published_time":"2024-09-27T19:11:08+00:00","article_modified_time":"2024-09-27T19:11:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-main.png","type":"image\/png"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julius","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Union Berlin vs Mainz","datePublished":"2024-09-27T19:11:08+00:00","dateModified":"2024-09-27T19:11:09+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/"},"wordCount":955,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-main.png","articleSection":["Head to Head"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/","url":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/","name":"Union Berlin vs Mainz - Lineups - H2H - Livescore - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-main.png","datePublished":"2024-09-27T19:11:08+00:00","dateModified":"2024-09-27T19:11:09+00:00","description":"Get the inside edge on the Union Berlin vs Mainz game with live scores and in-depth analysis you won't find anywhere else.","breadcrumb":{"@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/union-berlin-vs-mainz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-main.png","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/UB-vs-main.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/union-berlin-vs-mainz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Union Berlin vs Mainz"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/es\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/posts\/8219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/comments?post=8219"}],"version-history":[{"count":1,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/posts\/8219\/revisions"}],"predecessor-version":[{"id":8221,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/posts\/8219\/revisions\/8221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/media\/8220"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/media?parent=8219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/categories?post=8219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/es\/wp-json\/wp\/v2\/tags?post=8219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}