{"id":8591,"date":"2024-11-04T12:56:58","date_gmt":"2024-11-04T12:56:58","guid":{"rendered":"https:\/\/kickbol.com\/?p=8591"},"modified":"2024-11-04T12:56:58","modified_gmt":"2024-11-04T12:56:58","slug":"golden-arrows-vs-mamelodi-sundowns","status":"publish","type":"post","link":"https:\/\/kickbol.com\/de\/golden-arrows-vs-mamelodi-sundowns\/","title":{"rendered":"Golden Arrows gegen Mamelodi Sundowns"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM -->                <div id=\"ls-widget\" data-w=\"w_default\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/south-africa\/golden-arrows-mamelodi-sundowns\/1895460?w=w_default\" class=\"livescore-widget\"><\/div>                <script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script>                <!-- LIVESCORE WIDGET SOCCERSAPI.COM -->                            \n\n\n\n<p>Die B\u00fchne ist bereit f\u00fcr ein spannendes Duell in der DStv Premiership, denn Golden Arrows bereitet sich auf den Kampf gegen die m\u00e4chtigen Mamelodi Sundowns vor. Dieses Spiel verk\u00f6rpert die Essenz des Fu\u00dfballs, bei dem ein Au\u00dfenseiter, angetrieben von Leidenschaft und Entschlossenheit, einen Giganten des Spiels herausfordert. Es ist ein Kampf, der \u00fcber das blo\u00dfe Sammeln von Punkten hinausgeht; er ist ein Beweis f\u00fcr den Wettbewerbsgeist und die Unberechenbarkeit, die Fu\u00dfball zu einem so beliebten Sport machen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Head-to-Head: Eine Geschichte unterschiedlicher Schicksale<\/strong><\/h2>\n\n\n\n<p>Historisch betrachtet zeichnet der direkte Vergleich zwischen Golden Arrows und Mamelodi Sundowns das Bild einer einseitigen Rivalit\u00e4t. Sundowns, mit seinem Staraufgebot und unerm\u00fcdlichem Streben nach Troph\u00e4en, sind aus Begegnungen mit Arrows oft als Sieger hervorgegangen. Das Sch\u00f6ne am Fu\u00dfball ist jedoch seine F\u00e4higkeit, zu \u00fcberraschen, und jedes Spiel bietet dem Au\u00dfenseiter die M\u00f6glichkeit, das Drehbuch neu zu schreiben.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Statistik<\/th><th>Goldene Pfeile<\/th><th>Mamelodi Sonnenunterg\u00e4nge<\/th><\/tr><\/thead><tbody><tr><td>Gewinnt<\/td><td>5<\/td><td>25<\/td><\/tr><tr><td>Verluste<\/td><td>25<\/td><td>5<\/td><\/tr><tr><td>Zieht<\/td><td>10<\/td><td>10<\/td><\/tr><tr><td>Erzielte Tore<\/td><td>35<\/td><td>72<\/td><\/tr><tr><td>Gegentore<\/td><td>72<\/td><td>35<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Taktisches Schachspiel: Unterschiedliche Spielstile<\/strong><\/h3>\n\n\n\n<p>Golden Arrows spielt unter der F\u00fchrung seines klugen Managers normalerweise eine disziplinierte und organisierte 4-4-2-Formation. Ihr Schwerpunkt auf defensiver Solidit\u00e4t und schnellen Angriffs\u00fcberg\u00e4ngen erm\u00f6glicht es ihnen, gegen st\u00e4rkere Gegner anzutreten. Mit einer Mischung aus erfahrenen Veteranen und vielversprechenden Nachwuchsspielern zeichnet sich der Spielstil von Arrows durch seine Belastbarkeit und die F\u00e4higkeit aus, Konterchancen zu nutzen.<\/p>\n\n\n\n<p>Mamelodi Sundowns hingegen bevorzugt eine 4-3-3-Formation, die auf Ballbesitz basiert. Ihre technisch versierten Mittelfeldspieler und kreativen St\u00fcrmer bestimmen das Tempo des Spiels und schaffen eine F\u00fclle von Torchancen. Der Spielstil der Sundowns ist ein Beweis f\u00fcr ihren Ehrgeiz und ihren Wunsch, attraktiven, offensiven Fu\u00dfball zu spielen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Formationen und Schl\u00fcsselspieler: Die Architekten des Spiels<\/strong><\/h3>\n\n\n\n<p>Die 4-4-2-Formation der Golden Arrows bietet eine solide Verteidigungsbasis und erm\u00f6glicht gleichzeitig schnelle \u00dcberg\u00e4nge zum Angriff. Die beiden zentralen Mittelfeldspieler sind sowohl f\u00fcr die Verteidigung als auch f\u00fcr den Angriff zust\u00e4ndig, w\u00e4hrend die Au\u00dfenmittelfeldspieler f\u00fcr Breite und Unterst\u00fctzung im Angriff sorgen. Die beiden St\u00fcrmer, oft eine Kombination aus Zielspieler und Abr\u00e4umer, stellen eine st\u00e4ndige Bedrohung f\u00fcr die Verteidigung des Gegners dar.<\/p>\n\n\n\n<p>Die 4-3-3-Formation der Mamelodi Sundowns beruht auf der technischen Kompetenz und Kreativit\u00e4t ihrer Mittelfeldspieler. Die drei zentralen Mittelfeldspieler kontrollieren das Tempo des Spiels, w\u00e4hrend die Au\u00dfenst\u00fcrmer und Au\u00dfenverteidiger f\u00fcr Breite und Angriffsoptionen sorgen. Der einzige St\u00fcrmer, oft ein treffsicherer Vollstrecker, fungiert als zentraler Punkt im Angriff und nutzt die Chancen, die seine Teamkollegen schaffen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Geschichte und beste Torsch\u00fctzen aller Zeiten: Legenden und aufsteigende Stars<\/strong><\/h3>\n\n\n\n<p>Sowohl Golden Arrows als auch Mamelodi Sundowns haben eine reiche Geschichte in <a href=\"https:\/\/kickbol.com\/de\/premier-soccer-league\/\">S\u00fcdafrikanischer Fu\u00dfball<\/a>, wobei ihre jeweiligen besten Torsch\u00fctzen aller Zeiten einen besonderen Platz in den Herzen ihrer Fans haben. Diese Legenden, die ihre Namen in die Geschichtsb\u00fccher des Vereins eingraviert haben, dienen der heutigen Spielergeneration als Inspiration. Die aktuellen Mannschaften verf\u00fcgen auch \u00fcber vielversprechende junge Talente, die darauf brennen, in die Fu\u00dfstapfen ihrer Vorg\u00e4nger zu treten und ihr eigenes Verm\u00e4chtnis zu schaffen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Spieler im Blickpunkt: Die Game-Changer<\/strong><\/h3>\n\n\n\n<p>W\u00e4hrend sich die beiden Teams auf das Duell vorbereiten, werden mehrere Spieler eine entscheidende Rolle f\u00fcr den Ausgang des Spiels spielen. Der Kapit\u00e4n und Abwehrspieler der Golden Arrows wird mit seinen F\u00fchrungs- und Organisationsf\u00e4higkeiten die Aufgabe haben, die Verteidigung zu lenken und die Angriffsdrohungen der Sundowns zu vereiteln. Der talismanische Mittelfeldspieler der Mamelodi Sundowns wird mit seiner \u00dcbersicht, seinen P\u00e4ssen und seinem Talent, entscheidende Tore zu schie\u00dfen, der Dirigent ihrer Angriffe sein. Die Einzelk\u00e4mpfe zwischen diesen Schl\u00fcsselspielern k\u00f6nnten durchaus den Ausgang des Spiels bestimmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aktuelle Transferhistorie: Bauen f\u00fcr die Zukunft<\/strong><\/h3>\n\n\n\n<p>Sowohl Golden Arrows als auch Mamelodi Sundowns waren auf dem Transfermarkt aktiv, um ihre Mannschaften f\u00fcr die bevorstehenden Herausforderungen zu st\u00e4rken. Golden Arrows hat sich darauf konzentriert, Spieler zu verpflichten, die zu ihrer taktischen Herangehensweise passen und ihrem Kader mehr Tiefe verleihen k\u00f6nnen. Mamelodi Sundowns hat dank seiner Finanzkraft hochkar\u00e4tige Neuverpflichtungen get\u00e4tigt, um seinen bereits beeindruckenden Kader zu verst\u00e4rken. Die Transferaktivit\u00e4ten beider Vereine spiegeln ihren Ehrgeiz und ihren Wunsch wider, auf h\u00f6chstem Niveau mitzuspielen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fazit: Es erwartet Sie ein DStv-Premiership-Spektakel<\/strong><\/h2>\n\n\n\n<p>Das Duell zwischen Golden Arrows und Mamelodi Sundowns ist ein Beweis f\u00fcr die Sch\u00f6nheit des Fu\u00dfballs, bei dem ein Au\u00dfenseiter zu tr\u00e4umen wagt, bei dem auf dem Spielfeld taktische K\u00e4mpfe ausgetragen werden und individuelle Brillanz den Verlauf eines Spiels ver\u00e4ndern kann. Es ist ein Spiel, das den Wettbewerbsgeist und die Unberechenbarkeit verk\u00f6rpert, die Fu\u00dfball zu einem so beliebten Sport machen.<\/p>\n\n\n\n<p>W\u00e4hrend sich die beiden Teams auf den Duellkampf vorbereiten, erwartet die Fu\u00dfballgemeinde in S\u00fcdafrika ein Spiel voller Leidenschaft, Dramatik und unvergesslicher Momente. Golden Arrows wird mit seiner Widerstandsf\u00e4higkeit und Entschlossenheit versuchen, allen Widrigkeiten zu trotzen und den amtierenden Meister zu schlagen. Mamelodi Sundowns wird mit seinem Star-Kader und seiner Offensivst\u00e4rke versuchen, seine Dominanz zu behaupten und weiterhin nach Troph\u00e4en zu streben.<\/p>\n\n\n\n<p>Der Schlusspfiff markiert das Ende von neunzig Minuten intensiven Wettkampfs, doch die Wirkung dieses Spiels wird weit \u00fcber die Grenzen des Stadions hinaus nachhallen. Es wird eine Geschichte von verfolgten Tr\u00e4umen, \u00fcberwundenen Herausforderungen und dem unersch\u00fctterlichen Wettkampfgeist sein, der die DStv Premiership auszeichnet. Also lasst uns zusammenkommen, das sch\u00f6ne Spiel feiern und Zeuge der Entwicklung dieser fesselnden Begegnung werden, w\u00e4hrend Golden Arrows und Mamelodi Sundowns ihrer legend\u00e4ren Rivalit\u00e4t ein weiteres Kapitel hinzuf\u00fcgen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die B\u00fchne ist bereit f\u00fcr ein spannendes DStv Premiership-Spiel, denn Golden Arrows bereitet sich darauf vor, gegen die m\u00e4chtigen Mamelodi Sundowns anzutreten. Dieses Spiel verk\u00f6rpert die Essenz des Fu\u00dfballs, bei dem ein Au\u00dfenseiter, angetrieben von Leidenschaft und Entschlossenheit, einen Giganten des Spiels herausfordert. Es ist ein Kampf, der \u00fcber das blo\u00dfe Ansammeln von Punkten hinausgeht; es ist ein Beweis [\u2026]<\/p>","protected":false},"author":1,"featured_media":8592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-8591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Golden Arrows vs Mamelodi Sundowns - Lineups - H2H - Livescore - Kickbol<\/title>\n<meta name=\"description\" content=\"Get the inside edge on the Golden Arrows vs Mamelodi Sundowns game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/de\/golden-arrows-vs-mamelodi-sundowns\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Golden Arrows vs Mamelodi Sundowns - Lineups - H2H - Livescore - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Get the inside edge on the Golden Arrows vs Mamelodi Sundowns game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/de\/golden-arrows-vs-mamelodi-sundowns\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-04T12:56:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/GA-vs-MS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Golden Arrows vs Mamelodi Sundowns\",\"datePublished\":\"2024-11-04T12:56:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/\"},\"wordCount\":866,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GA-vs-MS.png\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/\",\"name\":\"Golden Arrows vs Mamelodi Sundowns - Lineups - H2H - Livescore - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GA-vs-MS.png\",\"datePublished\":\"2024-11-04T12:56:58+00:00\",\"description\":\"Get the inside edge on the Golden Arrows vs Mamelodi Sundowns game with live scores and in-depth analysis you won't find anywhere else.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GA-vs-MS.png\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GA-vs-MS.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/golden-arrows-vs-mamelodi-sundowns\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Golden Arrows vs Mamelodi Sundowns\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/de\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Golden Arrows vs Mamelodi Sundowns - Lineups - H2H - Livescore - Kickbol","description":"Get the inside edge on the Golden Arrows vs Mamelodi Sundowns game with live scores and in-depth analysis you won't find anywhere else.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/de\/golden-arrows-vs-mamelodi-sundowns\/","og_locale":"de_DE","og_type":"article","og_title":"Golden Arrows vs Mamelodi Sundowns - Lineups - H2H - Livescore - Kickbol","og_description":"Get the inside edge on the Golden Arrows vs Mamelodi Sundowns game with live scores and in-depth analysis you won't find anywhere else.","og_url":"https:\/\/kickbol.com\/de\/golden-arrows-vs-mamelodi-sundowns\/","og_site_name":"Kickbol","article_published_time":"2024-11-04T12:56:58+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/GA-vs-MS.png","type":"image\/png"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Julius","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Golden Arrows vs Mamelodi Sundowns","datePublished":"2024-11-04T12:56:58+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/"},"wordCount":866,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/GA-vs-MS.png","articleSection":["Head to Head"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/","url":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/","name":"Golden Arrows vs Mamelodi Sundowns - Lineups - H2H - Livescore - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/GA-vs-MS.png","datePublished":"2024-11-04T12:56:58+00:00","description":"Get the inside edge on the Golden Arrows vs Mamelodi Sundowns game with live scores and in-depth analysis you won't find anywhere else.","breadcrumb":{"@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/GA-vs-MS.png","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/11\/GA-vs-MS.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/golden-arrows-vs-mamelodi-sundowns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Golden Arrows vs Mamelodi Sundowns"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/de\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts\/8591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/comments?post=8591"}],"version-history":[{"count":1,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts\/8591\/revisions"}],"predecessor-version":[{"id":8593,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts\/8591\/revisions\/8593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/media\/8592"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/media?parent=8591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/categories?post=8591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/tags?post=8591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}