{"id":1681,"date":"2023-11-27T11:55:47","date_gmt":"2023-11-27T11:55:47","guid":{"rendered":"https:\/\/kickbol.com\/?p=1681"},"modified":"2024-06-25T10:48:43","modified_gmt":"2024-06-25T10:48:43","slug":"tottenham-hotspur-vs-brighton-hove-albion","status":"publish","type":"post","link":"https:\/\/kickbol.com\/de\/tottenham-hotspur-vs-brighton-hove-albion\/","title":{"rendered":"Tottenham Hotspur gegen Brighton &amp; Hove Albion"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM --><div id=\"ls-widget\" data-w=\"w_custom\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/match\/england\/tottenham-hotspur-brighton--hove-albion\/1844911?w=w_custom\" class=\"livescore-widget\"><\/div><script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script><!-- LIVESCORE WIDGET SOCCERSAPI.COM -->\n\n\n\n<p>Die Premier League ist Schauplatz einiger der legend\u00e4rsten und intensivsten Rivalit\u00e4ten im Weltfu\u00dfball, und das Aufeinandertreffen zwischen Tottenham Hotspur und Brighton &amp; Hove Albion bildet da keine Ausnahme. Diese beiden Vereine, die an entgegengesetzten Enden des englischen Fu\u00dfballspektrums stehen, haben eine Rivalit\u00e4t entwickelt, die ebenso faszinierend wie unberechenbar ist.<\/p>\n\n\n\n<p><strong>Eine Rivalit\u00e4t, die auf unterschiedlichen Stilen beruht<\/strong><\/p>\n\n\n\n<p>Der Kern der Rivalit\u00e4t zwischen Tottenham Hotspur und Brighton &amp; Hove Albion liegt in einem grundlegenden Unterschied in den Spielstilen. Tottenham, eine traditionelle Hochburg des englischen Fu\u00dfballs, ist f\u00fcr sein Offensivtalent und seine torreichen Spiele bekannt. Brighton hingegen hat einen pragmatischeren Ansatz gew\u00e4hlt und legt Wert auf defensive Solidit\u00e4t und schnelles Umschalten.<\/p>\n\n\n\n<p>Dieser Stilkontrast f\u00fchrt oft zu unterhaltsamen und unvorhersehbaren Spielen, da beide Teams versuchen, dem anderen ihre Spielstrategie aufzuzwingen. Tottenhams Angriffsst\u00e4rke kann \u00fcberw\u00e4ltigend sein, w\u00e4hrend Brightons Abwehrkraft frustrierend zu durchbrechen sein kann. Das Ergebnis ist eine Rivalit\u00e4t, die die Fans in Atem h\u00e4lt.<\/p>\n\n\n\n<p><strong>Eine Rivalit\u00e4t mit wachsender Bedeutung<\/strong><\/p>\n\n\n\n<p>In den letzten Jahren hat die Rivalit\u00e4t zwischen Tottenham Hotspur und Brighton &amp; Hove Albion an Bedeutung gewonnen. Beide Teams befinden sich in der Premier League auf einem Aufw\u00e4rtstrend, k\u00e4mpfen st\u00e4ndig um Pl\u00e4tze in der oberen Tabellenh\u00e4lfte und streben gelegentlich auch nach einer europ\u00e4ischen Qualifikation. Diese gesteigerte Wettbewerbsf\u00e4higkeit hat ihrer Rivalit\u00e4t noch mehr Intensit\u00e4t verliehen.<\/p>\n\n\n\n<p>Die Rivalit\u00e4t wurde auch durch die Anwesenheit mehrerer Starspieler verst\u00e4rkt. Tottenham kann mit Spielern wie Harry Kane, Son Heung-min und Hugo Lloris aufwarten, w\u00e4hrend Brighton Juwelen wie Yves Bissouma, Leandro Trossard und Robert S\u00e1nchez hervorgebracht hat. Diese individuellen Talente verleihen der ohnehin schon fesselnden Rivalit\u00e4t eine weitere Ebene der Spannung.<\/p>\n\n\n\n<p><strong>Direkter Vergleich<\/strong><\/p>\n\n\n\n<p>Hier ist eine Tabelle mit den direkten Duellen zwischen Tottenham Hotspur und Brighton &amp; Hove Albion:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Wettbewerb<\/th><th>Tottenham Hotspur gewinnt<\/th><th>Brighton &amp; Hove Albion gewinnt<\/th><th>Zieht<\/th><th>Tore f\u00fcr (Tottenham Hotspur)<\/th><th>Tore f\u00fcr (Brighton &amp; Hove Albion)<\/th><\/tr><\/thead><tbody><tr><td>Alle Wettbewerbe<\/td><td>8<\/td><td>5<\/td><td>5<\/td><td>28<\/td><td>28<\/td><\/tr><tr><td>Premier League<\/td><td>7<\/td><td>2<\/td><td>3<\/td><td>22<\/td><td>16<\/td><\/tr><tr><td>FA-Pokal<\/td><td>0<\/td><td>0<\/td><td>1<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>Ligapokal<\/td><td>1<\/td><td>2<\/td><td>1<\/td><td>4<\/td><td>5<\/td><\/tr><tr><td>Andere<\/td><td>0<\/td><td>1<\/td><td>0<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>Gesamt<\/td><td>9<\/td><td>6<\/td><td>5<\/td><td>36<\/td><td>36<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Wie die Tabelle zeigt, ist der direkte Vergleich zwischen Tottenham Hotspur und Brighton &amp; Hove Albion sehr ausgeglichen. Tottenham hat einen leichten Vorsprung, aber Brighton hat in den letzten Jahren einige wichtige Spiele gewonnen. Die Rivalit\u00e4t wird in den kommenden Jahren sicherlich weiterhin intensiv und unberechenbar bleiben.<\/p>\n\n\n\n<p><strong>Eine Rivalit\u00e4t mit globaler Reichweite<\/strong><\/p>\n\n\n\n<p>Die Popularit\u00e4t der Premier League hat daf\u00fcr gesorgt, dass die Rivalit\u00e4t zwischen Tottenham Hotspur und Brighton &amp; Hove Albion eine globale Reichweite hat. Ihre Spiele werden von Millionen von Zuschauern auf der ganzen Welt \u00fcbertragen und Fans aus allen Teilen der Welt werden von der Dramatik und Spannung ihrer Begegnungen angezogen.<\/p>\n\n\n\n<p>Die Rivalit\u00e4t hat auch dazu beigetragen, Spitzenspieler f\u00fcr beide Vereine zu gewinnen. Die Aussicht, sich mit einigen der besten Spieler der Welt zu messen, ist f\u00fcr aufstrebende Fu\u00dfballer ein gro\u00dfer Anziehungspunkt, und die Rivalit\u00e4t zwischen Tottenham Hotspur und Brighton &amp; Hove Albion bietet diesen Spielern eine Plattform, um ihr Talent zu zeigen.<\/p>\n\n\n\n<p><strong>Eine Rivalit\u00e4t, die die Premier League-Landschaft pr\u00e4gt<\/strong><\/p>\n\n\n\n<p>Die Rivalit\u00e4t zwischen Tottenham Hotspur und Brighton &amp; Hove Albion hat sich positiv auf die Premier League ausgewirkt. Ihre unterschiedlichen Spielstile und ihr unerm\u00fcdliches Streben nach Erfolg haben andere Vereine gezwungen, sich anzupassen und zu verbessern, was zur allgemeinen Steigerung des Spielniveaus in der Liga beigetragen hat.<\/p>\n\n\n\n<p>Die Rivalit\u00e4t hat der Premier League au\u00dferdem eine neue Dimension an Spannung und Unberechenbarkeit verliehen und sie zu einem der spannendsten Wettbewerbe im Weltfu\u00dfball gemacht. Fans auf der ganzen Welt sind fasziniert von dem Stilkonflikt und dem Potenzial f\u00fcr \u00dcberraschungen, und die Rivalit\u00e4t ist f\u00fcr die Anh\u00e4nger beider Vereine nach wie vor eine Quelle des Stolzes.<\/p>\n\n\n\n<p><strong>Abschluss<\/strong><\/p>\n\n\n\n<p>Die Rivalit\u00e4t zwischen Tottenham Hotspur und Brighton &amp; Hove Albion ist faszinierend und unberechenbar, wurzelt in kontrastierenden Stilen und wird immer bedeutender. Ihre Spiele sind ein Muss f\u00fcr jeden Fu\u00dfballfan, und ihre Rivalit\u00e4t wird die Fans sicherlich noch viele Jahre lang fesseln.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Premier League is home to some of the most iconic and intense rivalries in world football, and the clash between Tottenham Hotspur and Brighton &amp; Hove Albion is no exception. These two clubs, from opposite ends of the English football spectrum, have forged a rivalry that is as fascinating as it is unpredictable. A [&hellip;]<\/p>","protected":false},"author":1,"featured_media":5077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-1681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-head-to-head"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tottenham Hotspur vs\u00a0 Brighton &amp; Hove Albion - Lineups - H2H - Livescore - Kickbol<\/title>\n<meta name=\"description\" content=\"Get the inside edge on the Tottenham Hotspur vs Brighton game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/de\/tottenham-hotspur-vs-brighton-hove-albion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tottenham Hotspur vs\u00a0 Brighton &amp; Hove Albion - Lineups - H2H - Livescore - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Get the inside edge on the Tottenham Hotspur vs Brighton game with live scores and in-depth analysis you won&#039;t find anywhere else.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/de\/tottenham-hotspur-vs-brighton-hove-albion\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T11:55:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-25T10:48:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/tot-v-bri.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"205\" \/>\n\t<meta property=\"og:image:height\" content=\"127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Tottenham Hotspur vs\u00a0 Brighton &#038; Hove Albion\",\"datePublished\":\"2023-11-27T11:55:47+00:00\",\"dateModified\":\"2024-06-25T10:48:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/\"},\"wordCount\":638,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/tot-v-bri.jpeg\",\"articleSection\":[\"Head to Head\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/\",\"name\":\"Tottenham Hotspur vs\u00a0 Brighton & Hove Albion - Lineups - H2H - Livescore - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/tot-v-bri.jpeg\",\"datePublished\":\"2023-11-27T11:55:47+00:00\",\"dateModified\":\"2024-06-25T10:48:43+00:00\",\"description\":\"Get the inside edge on the Tottenham Hotspur vs Brighton game with live scores and in-depth analysis you won't find anywhere else.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/tot-v-bri.jpeg\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/tot-v-bri.jpeg\",\"width\":205,\"height\":127},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/tottenham-hotspur-vs-brighton-hove-albion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tottenham Hotspur vs\u00a0 Brighton &#038; Hove Albion\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/de\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tottenham Hotspur vs\u00a0 Brighton & Hove Albion - Lineups - H2H - Livescore - Kickbol","description":"Get the inside edge on the Tottenham Hotspur vs Brighton game with live scores and in-depth analysis you won't find anywhere else.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/de\/tottenham-hotspur-vs-brighton-hove-albion\/","og_locale":"de_DE","og_type":"article","og_title":"Tottenham Hotspur vs\u00a0 Brighton & Hove Albion - Lineups - H2H - Livescore - Kickbol","og_description":"Get the inside edge on the Tottenham Hotspur vs Brighton game with live scores and in-depth analysis you won't find anywhere else.","og_url":"https:\/\/kickbol.com\/de\/tottenham-hotspur-vs-brighton-hove-albion\/","og_site_name":"Kickbol","article_published_time":"2023-11-27T11:55:47+00:00","article_modified_time":"2024-06-25T10:48:43+00:00","og_image":[{"width":205,"height":127,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/tot-v-bri.jpeg","type":"image\/jpeg"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Julius","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Tottenham Hotspur vs\u00a0 Brighton &#038; Hove Albion","datePublished":"2023-11-27T11:55:47+00:00","dateModified":"2024-06-25T10:48:43+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/"},"wordCount":638,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/tot-v-bri.jpeg","articleSection":["Head to Head"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/","url":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/","name":"Tottenham Hotspur vs\u00a0 Brighton & Hove Albion - Lineups - H2H - Livescore - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/tot-v-bri.jpeg","datePublished":"2023-11-27T11:55:47+00:00","dateModified":"2024-06-25T10:48:43+00:00","description":"Get the inside edge on the Tottenham Hotspur vs Brighton game with live scores and in-depth analysis you won't find anywhere else.","breadcrumb":{"@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/tot-v-bri.jpeg","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/11\/tot-v-bri.jpeg","width":205,"height":127},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/tottenham-hotspur-vs-brighton-hove-albion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Tottenham Hotspur vs\u00a0 Brighton &#038; Hove Albion"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/de\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts\/1681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/comments?post=1681"}],"version-history":[{"count":3,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts\/1681\/revisions"}],"predecessor-version":[{"id":5346,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/posts\/1681\/revisions\/5346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/media\/5077"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/media?parent=1681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/categories?post=1681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/de\/wp-json\/wp\/v2\/tags?post=1681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}