{"id":1283,"date":"2023-10-03T01:51:26","date_gmt":"2023-10-03T01:51:26","guid":{"rendered":"https:\/\/kickbol.com\/pec-zwolle-fc\/"},"modified":"2024-08-02T11:03:21","modified_gmt":"2024-08-02T11:03:21","slug":"pec-zwolle-fc","status":"publish","type":"post","link":"https:\/\/kickbol.com\/ar\/pec-zwolle-fc\/","title":{"rendered":"\u0646\u0627\u062f\u064a \u0628\u064a\u0643 \u0632\u0641\u0648\u0644\u0647 \u0644\u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645"},"content":{"rendered":"<!-- LIVESCORE WIDGET SOCCERSAPI.COM --><div id=\"ls-widget\" data-w=\"w_custom\" data-height=\"1200\" data-url=\"https:\/\/ls.soccersapi.com\/teams\/pec-zwolle\/2466?w=w_custom\" class=\"livescore-widget\"><\/div><script type=\"text\/javascript\" src=\"https:\/\/ls.soccersapi.com\/widget\/res\/w_custom\/widget.js\"><\/script><!-- LIVESCORE WIDGET SOCCERSAPI.COM -->\n\n\n<h2>\u0646\u0627\u062f\u064a \u0628\u064a\u0643 \u0632\u0641\u0648\u0644\u0647 \u0644\u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u2013 \u0641\u062e\u0631 \u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0627\u0644\u0647\u0648\u0644\u0646\u062f\u064a\u0629<\/h2>\n<h3>\u0645\u0642\u062f\u0645\u0629<\/h3>\n<p>\u0646\u0627\u062f\u064a \u0628\u064a\u0643 \u0632\u0641\u0648\u0644\u0647 \u0644\u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645\u060c \u0627\u0644\u0645\u0639\u0631\u0648\u0641 \u0628\u0627\u0633\u0645 PEC Zwolle\u060c \u0647\u0648 \u0646\u0627\u062f\u064a \u0643\u0631\u0629 \u0642\u062f\u0645 \u0645\u062d\u062a\u0631\u0641 \u0645\u0642\u0631\u0647 \u0645\u062f\u064a\u0646\u0629 \u0632\u0641\u0648\u0644\u0647 \u0628\u0647\u0648\u0644\u0646\u062f\u0627. \u062a\u0623\u0633\u0633 \u0627\u0644\u0646\u0627\u062f\u064a \u0641\u064a \u0639\u0627\u0645 1910 \u0648\u0645\u0646\u0630 \u0630\u0644\u0643 \u0627\u0644\u062d\u064a\u0646 \u0623\u062b\u0628\u062a \u0646\u0641\u0633\u0647 \u0643\u0648\u0627\u062d\u062f \u0645\u0646 \u0623\u0628\u0631\u0632 \u0627\u0644\u0623\u0646\u062f\u064a\u0629 \u0641\u064a \u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0627\u0644\u0647\u0648\u0644\u0646\u062f\u064a\u0629. \u064a\u062a\u0645\u062a\u0639 \u0646\u0627\u062f\u064a \u0628\u064a\u0643 \u0632\u0641\u0648\u0644\u0647 \u0644\u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0628\u062a\u0627\u0631\u064a\u062e \u063a\u0646\u064a \u0648\u0646\u062c\u0627\u062d\u0627\u062a \u0639\u062f\u064a\u062f\u0629 \u0648\u0641\u0631\u064a\u0642 \u0645\u0648\u0647\u0648\u0628 \u0645\u0646 \u0627\u0644\u0644\u0627\u0639\u0628\u064a\u0646.<\/p>\n<h3>\u0646\u062c\u0627\u062d\u0627\u062a \u0648\u0625\u0646\u062c\u0627\u0632\u0627\u062a \u0627\u0644\u0646\u0627\u062f\u064a<\/h3>\n<p>\u062d\u0642\u0642 \u0646\u0627\u062f\u064a PEC Zwolle FC \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0625\u0646\u062c\u0627\u0632\u0627\u062a \u0639\u0644\u0649 \u0645\u0631 \u0627\u0644\u0633\u0646\u064a\u0646. \u0641\u0642\u062f \u0641\u0627\u0632 \u0628\u0643\u0623\u0633 \u0647\u0648\u0644\u0646\u062f\u0627 \u0645\u0631\u062a\u064a\u0646\u060c \u0641\u064a \u0639\u0627\u0645\u064a 2014 \u06482020\u060c \u0648\u0647\u0645\u0627 \u0623\u0643\u062b\u0631 \u0628\u0637\u0648\u0644\u0627\u062a \u0627\u0644\u0643\u0623\u0633 \u0627\u0644\u0645\u062d\u0644\u064a\u0629 \u0634\u0647\u0631\u0629 \u0641\u064a \u0647\u0648\u0644\u0646\u062f\u0627. \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0630\u0644\u0643\u060c \u062d\u0642\u0642 \u0646\u062c\u0627\u062d\u064b\u0627 \u0641\u064a \u062f\u0648\u0631\u064a \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 \u0627\u0644\u0647\u0648\u0644\u0646\u062f\u064a\u060c \u0648\u0636\u0645\u0646 \u0627\u0644\u0635\u0639\u0648\u062f \u0625\u0644\u0649 \u062f\u0648\u0631\u064a \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0639\u062f\u0629 \u0645\u0631\u0627\u062a \u0637\u0648\u0627\u0644 \u062a\u0627\u0631\u064a\u062e\u0647.<\/p>\n<h3>\u062c\u062f\u0648\u0644 \u0627\u0644\u0645\u0646\u0627\u0641\u0633\u064a\u0646 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u064a\u0646<\/h3>\n<table>\n<tbody>\n<tr>\n<th>\u0627\u0644\u0641\u0631\u064a\u0642 \u0627\u0644\u0645\u0646\u0627\u0641\u0633<\/th>\n<th>\u0639\u062f\u062f \u0627\u0644\u0645\u0628\u0627\u0631\u064a\u0627\u062a \u0627\u0644\u062a\u064a \u0644\u0639\u0628\u062a<\/th>\n<th>\u0627\u0644\u0641\u0648\u0632<\/th>\n<th>\u0627\u0644\u062a\u0639\u0627\u062f\u0644\u0627\u062a<\/th>\n<th>\u062e\u0633\u0627\u0626\u0631<\/th>\n<\/tr>\n<tr>\n<td>\u0623\u064a\u0627\u0643\u0633 \u0623\u0645\u0633\u062a\u0631\u062f\u0627\u0645<\/td>\n<td>34<\/td>\n<td>5<\/td>\n<td>9<\/td>\n<td>20<\/td>\n<\/tr>\n<tr>\n<td>\u0646\u0627\u062f\u064a \u062a\u0641\u064a\u0646\u062a\u064a<\/td>\n<td>32<\/td>\n<td>10<\/td>\n<td>8<\/td>\n<td>14<\/td>\n<\/tr>\n<tr>\n<td>\u0646\u0627\u062f\u064a \u0647\u064a\u0631\u064a\u0646\u0641\u064a\u0646 \u0627\u0644\u0631\u064a\u0627\u0636\u064a<\/td>\n<td>28<\/td>\n<td>13<\/td>\n<td>7<\/td>\n<td>8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>\u0623\u0634\u0647\u0631 \u0627\u0644\u0644\u0627\u0639\u0628\u064a\u0646<\/h3>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>\u0631\u0648\u062f \u0643\u0631\u0648\u0644<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>\u0644\u064a\u0648 \u0628\u064a\u0646\u0647\u0627\u0643\u0631<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>\u064a\u0648\u0647\u0627\u0646 \u062f\u064a\u0631\u0643\u0633\u064a\u0646<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>\u0648\u064a\u0644\u064a\u0645 \u0641\u0627\u0646 \u0647\u0627\u0646\u064a\u062c\u064a\u0645<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>\u0623\u0639\u0644\u0649 \u0627\u0644\u0647\u062f\u0627\u0641\u064a\u0646<\/h3>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>\u0647\u0627\u0646\u0632 \u0647\u0627\u062a\u0628\u0648\u0631 \u2013 46 \u0647\u062f\u0641\u064b\u0627<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>\u0644\u064a\u0648 \u0643\u0648\u0628\u0645\u0627\u0646 \u2013 107 \u0623\u0647\u062f\u0627\u0641<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>\u0641\u0631\u064a\u062f \u0628\u064a\u0646\u0633\u0648\u0646 \u2013 52 \u0647\u062f\u0641\u064b\u0627<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>\u0647\u0646\u0643 \u062a\u064a\u0645\u0631 \u2013 64 \u0647\u062f\u0641\u064b\u0627<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h3>\u0627\u0644\u0623\u0633\u0626\u0644\u0629 \u0627\u0644\u0634\u0627\u0626\u0639\u0629<\/h3>\n<h4>\u0633: \u0645\u062a\u0649 \u062a\u0623\u0633\u0633 \u0646\u0627\u062f\u064a PEC Zwolle FC\u061f<\/h4>\n<p>\u062c: \u062a\u0623\u0633\u0633 \u0646\u0627\u062f\u064a PEC Zwolle \u0644\u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0641\u064a \u0639\u0627\u0645 1910.<\/p>\n<h4>\u0633: \u0643\u0645 \u0645\u0631\u0629 \u0641\u0627\u0632 \u0646\u0627\u062f\u064a PEC Zwolle FC \u0628\u0643\u0623\u0633 \u0647\u0648\u0644\u0646\u062f\u0627\u061f<\/h4>\n<p>\u0623: \u0641\u0627\u0632 \u0646\u0627\u062f\u064a PEC Zwolle FC \u0628\u0643\u0623\u0633 \u0647\u0648\u0644\u0646\u062f\u0627 \u0645\u0631\u062a\u064a\u0646\u060c \u0641\u064a \u0639\u0627\u0645\u064a 2014 \u06482020.<\/p>\n<h4>\u0633: \u0645\u0646 \u0647\u0648 \u0627\u0644\u0647\u062f\u0627\u0641 \u0627\u0644\u0623\u0639\u0644\u0649 \u0641\u064a \u062a\u0627\u0631\u064a\u062e \u0646\u0627\u062f\u064a PEC Zwolle FC\u061f<\/h4>\n<p>\u0623: \u064a\u062d\u0645\u0644 \u0644\u064a\u0648 \u0643\u0648\u0628\u0645\u0627\u0646 \u0627\u0644\u0631\u0642\u0645 \u0627\u0644\u0642\u064a\u0627\u0633\u064a \u0644\u0623\u0639\u0644\u0649 \u0639\u062f\u062f \u0645\u0646 \u0627\u0644\u0623\u0647\u062f\u0627\u0641 \u0627\u0644\u0645\u0633\u062c\u0644\u0629 \u0644\u0641\u0631\u064a\u0642 PEC Zwolle FC\u060c \u0628\u0648\u0627\u0642\u0639 107 \u0623\u0647\u062f\u0627\u0641.<\/p>\n<h3>\u062e\u0627\u062a\u0645\u0629<\/h3>\n<p>\u064a\u062a\u0645\u062a\u0639 \u0646\u0627\u062f\u064a PEC Zwolle FC \u0628\u062a\u0627\u0631\u064a\u062e \u0631\u0627\u0626\u0639 \u0641\u064a \u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0627\u0644\u0647\u0648\u0644\u0646\u062f\u064a\u0629\u060c \u0645\u0639 \u0646\u062c\u0627\u062d\u0627\u062a \u0648\u0625\u0646\u062c\u0627\u0632\u0627\u062a \u0645\u0644\u062d\u0648\u0638\u0629. \u0625\u0646 \u0627\u0646\u062a\u0635\u0627\u0631\u0627\u062a \u0627\u0644\u0646\u0627\u062f\u064a \u0641\u064a \u0643\u0623\u0633 \u0647\u0648\u0644\u0646\u062f\u0627\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0635\u0639\u0648\u062f\u0647 \u0625\u0644\u0649 \u0627\u0644\u062f\u0648\u0631\u064a \u0627\u0644\u0647\u0648\u0644\u0646\u062f\u064a \u0627\u0644\u0645\u0645\u062a\u0627\u0632\u060c \u062a\u062b\u0628\u062a \u0642\u062f\u0631\u062a\u0647 \u0627\u0644\u062a\u0646\u0627\u0641\u0633\u064a\u0629 \u0648\u062a\u0635\u0645\u064a\u0645\u0647. \u0643\u0645\u0627 \u0634\u0647\u062f \u0646\u0627\u062f\u064a PEC Zwolle FC \u0623\u064a\u0636\u064b\u0627 \u0628\u0639\u0636 \u0627\u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0627\u0644\u0645\u0634\u0647\u0648\u0631\u064a\u0646 \u0627\u0644\u0630\u064a\u0646 \u0632\u064a\u0646\u0648\u0627 \u0641\u0631\u0642\u0647\u0645 \u0639\u0644\u0649 \u0645\u0631 \u0627\u0644\u0633\u0646\u064a\u0646. \u0645\u0639 \u0642\u0627\u0639\u062f\u0629 \u062c\u0645\u0627\u0647\u064a\u0631\u064a\u0629 \u0645\u062a\u062d\u0645\u0633\u0629 \u0648\u062a\u0641\u0627\u0646\u064a \u0644\u0627\u0639\u0628\u064a\u0647\u060c \u064a\u0648\u0627\u0635\u0644 \u0646\u0627\u062f\u064a PEC Zwolle FC \u062a\u0631\u0643 \u0628\u0635\u0645\u0629 \u0639\u0644\u0649 \u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0627\u0644\u0647\u0648\u0644\u0646\u062f\u064a\u0629.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pec Zwolle FC &#8211; The Pride of Dutch Football Introduction Pec Zwolle FC, commonly known as PEC Zwolle, is a professional football club based in Zwolle, Netherlands. The club was founded in 1910 and has since established itself as one of the prominent clubs in Dutch football. PEC Zwolle FC has a rich history, numerous [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104],"tags":[],"class_list":["post-1283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-teams"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pec Zwolle FC - Kickbol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kickbol.com\/ar\/pec-zwolle-fc\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pec Zwolle FC - Kickbol\" \/>\n<meta property=\"og:description\" content=\"Pec Zwolle FC &#8211; The Pride of Dutch Football Introduction Pec Zwolle FC, commonly known as PEC Zwolle, is a professional football club based in Zwolle, Netherlands. The club was founded in 1910 and has since established itself as one of the prominent clubs in Dutch football. PEC Zwolle FC has a rich history, numerous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kickbol.com\/ar\/pec-zwolle-fc\/\" \/>\n<meta property=\"og:site_name\" content=\"Kickbol\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-03T01:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T11:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/10\/pec.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"142\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/\"},\"author\":{\"name\":\"Julius\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\"},\"headline\":\"Pec Zwolle FC\",\"datePublished\":\"2023-10-03T01:51:26+00:00\",\"dateModified\":\"2024-08-02T11:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pec.jpeg\",\"articleSection\":[\"Teams\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/\",\"name\":\"Pec Zwolle FC - Kickbol\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pec.jpeg\",\"datePublished\":\"2023-10-03T01:51:26+00:00\",\"dateModified\":\"2024-08-02T11:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pec.jpeg\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pec.jpeg\",\"width\":142,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kickbol.com\\\/pec-zwolle-fc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kickbol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pec Zwolle FC\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#website\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"name\":\"Kickbol\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/kickbol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#organization\",\"name\":\"Kickbol\",\"url\":\"http:\\\/\\\/kickbol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"contentUrl\":\"https:\\\/\\\/kickbol.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp\",\"width\":1024,\"height\":693,\"caption\":\"Kickbol\"},\"image\":{\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kickbol.com\\\/#\\\/schema\\\/person\\\/f53207ba8ed540a66a98bb9ca4daa786\",\"name\":\"Julius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g\",\"caption\":\"Julius\"},\"sameAs\":[\"https:\\\/\\\/kickbol.com\"],\"url\":\"https:\\\/\\\/kickbol.com\\\/ar\\\/author\\\/sparrowjackcr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pec Zwolle FC - Kickbol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kickbol.com\/ar\/pec-zwolle-fc\/","og_locale":"ar_AR","og_type":"article","og_title":"Pec Zwolle FC - Kickbol","og_description":"Pec Zwolle FC &#8211; The Pride of Dutch Football Introduction Pec Zwolle FC, commonly known as PEC Zwolle, is a professional football club based in Zwolle, Netherlands. The club was founded in 1910 and has since established itself as one of the prominent clubs in Dutch football. PEC Zwolle FC has a rich history, numerous [&hellip;]","og_url":"https:\/\/kickbol.com\/ar\/pec-zwolle-fc\/","og_site_name":"Kickbol","article_published_time":"2023-10-03T01:51:26+00:00","article_modified_time":"2024-08-02T11:03:21+00:00","og_image":[{"width":142,"height":180,"url":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/10\/pec.jpeg","type":"image\/jpeg"}],"author":"Julius","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"Julius","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#article","isPartOf":{"@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/"},"author":{"name":"Julius","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786"},"headline":"Pec Zwolle FC","datePublished":"2023-10-03T01:51:26+00:00","dateModified":"2024-08-02T11:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/"},"wordCount":317,"publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"image":{"@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/10\/pec.jpeg","articleSection":["Teams"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/","url":"https:\/\/kickbol.com\/pec-zwolle-fc\/","name":"Pec Zwolle FC - Kickbol","isPartOf":{"@id":"http:\/\/kickbol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#primaryimage"},"image":{"@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#primaryimage"},"thumbnailUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/10\/pec.jpeg","datePublished":"2023-10-03T01:51:26+00:00","dateModified":"2024-08-02T11:03:21+00:00","breadcrumb":{"@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kickbol.com\/pec-zwolle-fc\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#primaryimage","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/10\/pec.jpeg","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2023\/10\/pec.jpeg","width":142,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/kickbol.com\/pec-zwolle-fc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kickbol.com\/"},{"@type":"ListItem","position":2,"name":"Pec Zwolle FC"}]},{"@type":"WebSite","@id":"http:\/\/kickbol.com\/#website","url":"http:\/\/kickbol.com\/","name":"Kickbol","description":"","publisher":{"@id":"http:\/\/kickbol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/kickbol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"http:\/\/kickbol.com\/#organization","name":"Kickbol","url":"http:\/\/kickbol.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/","url":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","contentUrl":"https:\/\/kickbol.com\/wp-content\/uploads\/2024\/09\/cropped-DALL\u00b7E-2024-09-19-10.49.34-A-modern-logo-for-Kickbol.com-a-soccer-statistics-website.-The-logo-features-a-sleek-soccer-ball-with-subtle-graph-or-chart-lines-incorporated-into-i.webp","width":1024,"height":693,"caption":"Kickbol"},"image":{"@id":"http:\/\/kickbol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/kickbol.com\/#\/schema\/person\/f53207ba8ed540a66a98bb9ca4daa786","name":"Julius","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c265140e1930a0acd868b2003ee7374b9b8f400d8a8bbf91ca20a6e9cfd50393?s=96&d=mm&r=g","caption":"Julius"},"sameAs":["https:\/\/kickbol.com"],"url":"https:\/\/kickbol.com\/ar\/author\/sparrowjackcr\/"}]}},"_links":{"self":[{"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/posts\/1283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/comments?post=1283"}],"version-history":[{"count":2,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/posts\/1283\/revisions"}],"predecessor-version":[{"id":6391,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/posts\/1283\/revisions\/6391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/media\/1443"}],"wp:attachment":[{"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/media?parent=1283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/categories?post=1283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kickbol.com\/ar\/wp-json\/wp\/v2\/tags?post=1283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}